{"id":10930,"date":"2024-11-04T12:34:07","date_gmt":"2024-11-04T15:34:07","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=10930"},"modified":"2024-11-08T13:44:43","modified_gmt":"2024-11-08T16:44:43","slug":"por-que-el-girasol-es-una-apuesta-recomendable-para-productores-del-noroeste-bonaerense","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/por-que-el-girasol-es-una-apuesta-recomendable-para-productores-del-noroeste-bonaerense\/","title":{"rendered":"\u00bfPor qu\u00e9 el girasol es una apuesta recomendable para productores del noroeste bonaerense?"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8bedd783110b417b6703ee14150b2bed\"><strong><em>En los campos del noroeste bonaerense, el girasol vuelve a ganar terreno. Las caracter\u00edsticas fisiol\u00f3gicas y las condiciones de mercado lo convierten en una opci\u00f3n interesante especialmente en un contexto de sequ\u00eda y precios internacionales favorables.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f88bbbf330ba7a6e973af0cbf013fe3f\">El girasol, un cultivo tradicional en el noroeste bonaerense, est\u00e1 regresando a los campos de la regi\u00f3n. Este renacer del girasol no es casualidad, sino el resultado de una combinaci\u00f3n de factores clim\u00e1ticos y econ\u00f3micos que lo hacen una opci\u00f3n estrat\u00e9gica en un contexto desafiante para el sector agropecuario.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-500e377c8e271e08e175c78ea5e2b1ff\"><strong>Seg\u00fan el ingeniero agr\u00f3nomo Juan Ignacio Fari\u00f1a, \u201ca nivel fisiol\u00f3gico, el girasol est\u00e1 clasificado como especie anisoh\u00eddrica, con menor sensibilidad estom\u00e1tica, capacidad de ajustes osm\u00f3ticos y buena distribuci\u00f3n de ra\u00edces\u201d.<\/strong>&nbsp;Estas caracter\u00edsticas permiten que el girasol tenga una importancia en ambientes con baja disponibilidad de agua. \u201cCon menos mil\u00edmetros comparados con soja y ma\u00edz, el cultivo puede alcanzar potenciales de rendimiento\u201d, agrega Fari\u00f1a. Esta tolerancia a condiciones de sequ\u00eda es particularmente relevante en el contexto actual, donde las lluvias han estado por debajo de los promedios anuales en las \u00faltimas campa\u00f1as. Esta situaci\u00f3n ha puesto en jaque a los cultivos de gruesas tradicionales, y el girasol ha comenzado a ganar terreno.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a7bd19419cde10ccb50982f12265f923\">El ingeniero explica tambi\u00e9n que el cultivo del girasol en la regi\u00f3n no es una novedad. Hace treinta a\u00f1os, el girasol era un actor habitual en el paisaje rural del noroeste bonaerense. Sin embargo,\u00a0<strong>\u201cel auge de la soja a finales de los 90s, acompa\u00f1ado de buenos precios internacionales, buenas condiciones clim\u00e1ticas y manejo simplificado, desplaz\u00f3 al girasol a zonas m\u00e1s restrictivas, como el oeste pampeano\u201d. Ahora, con el conflicto entre Rusia y Ucrania que ha disparado los precios internacionales de los aceites, muchos productores vuelven a considerar esta oleaginosa en sus rotaciones.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5c7b9146ef4052f7cde669669f2a9323\">M\u00e1s all\u00e1 de los beneficios econ\u00f3micos y de resistencia, el girasol ofrece otras ventajas que pueden resultar atractivas para el productor.\u00a0<strong>\u201cSi queremos diversificar el sistema, escalonar cosechas, sembrar verdeos de invierno, ahorrar en flete y, sobre todo, si tenemos un ambiente restrictivo donde la potencialidad del cultivo de soja es media o baja, deber\u00edamos dejar entrar a la cancha al girasol. \u201d, sostiene Fari\u00f1a.<\/strong>\u00a0La posibilidad de diversificar cultivos y de utilizar el girasol en campos con menores rendimientos potenciales refuerza su papel como alternativa resiliente y rentable.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d03ac8ff69f76fe29de0fbf7e6d53f92\">En definitiva, el retorno del girasol al noroeste bonaerense no solo responde a su resistencia frente a condiciones de estr\u00e9s h\u00eddrico y los altos precios en el mercado global, sino tambi\u00e9n a su capacidad de aportar flexibilidad y solidez a los sistemas productivos de la regi\u00f3n.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los campos del noroeste bonaerense, el girasol vuelve a ganar terreno. Las caracter\u00edsticas fisiol\u00f3gicas y las condiciones de mercado lo convierten en una opci\u00f3n interesante especialmente en un contexto de sequ\u00eda y precios internacionales favorables. El girasol, un cultivo tradicional en el noroeste bonaerense, est\u00e1 regresando a los campos de la regi\u00f3n. Este renacer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32,38,31,6,33],"tags":[],"class_list":["post-10930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro-negocios","category-clima","category-importantes","category-interes-general","category-rural"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2024\/11\/GIRASOLVALIDA.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/10930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=10930"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/10930\/revisions"}],"predecessor-version":[{"id":10932,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/10930\/revisions\/10932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/10931"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=10930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=10930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=10930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}