{"id":11216,"date":"2024-12-24T00:24:07","date_gmt":"2024-12-24T03:24:07","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=11216"},"modified":"2024-12-29T23:23:28","modified_gmt":"2024-12-30T02:23:28","slug":"ameghino-odilia-villegas-gano-el-premio-mayor-de-la-rifa-de-bomberos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-odilia-villegas-gano-el-premio-mayor-de-la-rifa-de-bomberos\/","title":{"rendered":"Ameghino-Odilia Villegas gan\u00f3 el premio mayor de la rifa de bomberos."},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4e584277235e3118507e6a02a4713157\"><strong><em>La sexta gran rifa anual de bomberos lleg\u00f3 a su fin y la ganadora de los diez millones fu\u00e9 la Ameghinense Odilia Tita Villegas.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d064290f3052f34f439b000fc38e8c73\">En el sorteo de este Lunes por Loter\u00eda Nocturna de la Pcia de Bs As se conocieron los ganadores del \u00faltimo sorteo de la gran rifa que ten\u00eda en circulacion la institucion Bomberos Voluntarios de Ameghino, r\u00e1pidamente se dieron a conocer los ganadores de los 10 premios finales.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c7f237e19065f3e54c313e300aba2274\"><strong><em>GANADORES.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4d8647e69612b8578dea2cd5a3909945\"><strong><em>Primer premio 10 MILLONES de PESOS  N\u00b0174 Odilia (TITA) Villegas, <\/em><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-88368a508a4f1d507db858892a212d53\">Segundo premio MOTO Gilera 110 c.c el N\u00b0 035 Stella Muller-Tercer premio FREEZER  N\u00b0417 Lorena Sierra-Cuarto premio TV 40&#8243;  N\u00b0 034 Ganadera El Rosario-Quinto premio Juego de Jard\u00edn c\/ sombrilla  N\u00b0249 Susana Fantone-Sexto premio COCINA  N\u00b0219 Ana Passoni (Lincoln)- S\u00e9ptimo premio BICICLETA MTB N\u00b0155 Roberto Chora- Octavo premio TERMO ELECT.  N\u00b0745 Fiamma Ochoa- Noveno premio 2 REPOSERAS  N\u00b0893 Marisa S\u00e1nchez- D\u00e9cimo premio PROCESADORA  N\u00b0930 Rub\u00e9n Foresi.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-734bbfa4fbab8f8d21684676181c7e05\">Desde la comision y cuerpo activo hicieron extensivas las felicitaciones y agradecieron la adquisicion de la rifa. A su ves informaron que en breve estar\u00e1 en circulaci\u00f3n la s\u00e9ptima  rifa anual con un premio final de <strong>veinte millones de pesos ($ 20.000.000)<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9ac00cf961d1ea846fe5a532228b76c6\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sexta gran rifa anual de bomberos lleg\u00f3 a su fin y la ganadora de los diez millones fu\u00e9 la Ameghinense Odilia Tita Villegas. En el sorteo de este Lunes por Loter\u00eda Nocturna de la Pcia de Bs As se conocieron los ganadores del \u00faltimo sorteo de la gran rifa que ten\u00eda en circulacion la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,37],"tags":[],"class_list":["post-11216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2024\/12\/BOMBEROS2-VALID.jpg?fit=494%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=11216"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11216\/revisions"}],"predecessor-version":[{"id":11218,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11216\/revisions\/11218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/11217"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=11216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=11216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=11216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}