{"id":11809,"date":"2025-05-06T11:38:11","date_gmt":"2025-05-06T14:38:11","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=11809"},"modified":"2025-05-08T15:04:29","modified_gmt":"2025-05-08T18:04:29","slug":"rivadavia-sera-sede-del-encuentro-regional-de-organizacion-municipal-de-la-defensa-civil","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/rivadavia-sera-sede-del-encuentro-regional-de-organizacion-municipal-de-la-defensa-civil\/","title":{"rendered":"Rivadavia ser\u00e1 sede del encuentro regional de Organizaci\u00f3n Municipal de la Defensa Civil\u00a0"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2142b6e3c947ecb65434e54944eb55f5\"><strong>El taller, que involucrar\u00e1 a 11 distritos de la regi\u00f3n, se llevar\u00e1 a cabo en la ciudad de Am\u00e9rica, y contar\u00e1 con la presencia de funcionarios provinciales y municipales de las \u00e1reas involucradas.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-ab9fc7d56874465a1d00d7d4696a3ea0\">La capacitaci\u00f3n estar\u00e1 a cargo de la directora bonaerense de Fortalecimiento del Sistema de Defensa Civil, Vanesa Misseri, y contar\u00e1 con la presencia de representantes de Rivadavia, General Villegas, Carlos Tejedor, Trenque Lauquen, Tres Lomas, Salliquel\u00f3, Pehuaj\u00f3, Carlos Casares, Hip\u00f3lito Yrigoyen y Daireaux.&nbsp;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-32c827c44a7533ece6eac313c4c8ef1c\">El organismo provincial, dependiente del Ministerio de Seguridad, cuenta con un programa de fortalecimiento para municipios que, coordinado con las distintas \u00e1reas, trabajan en la prevenci\u00f3n de eventos de emergencia, para evitar, reducir y reparar los efectos de los eventos adversos resultantes de la acci\u00f3n de agentes naturales o antr\u00f3picos susceptibles de ocasionar da\u00f1o a la poblaci\u00f3n, o a los bienes p\u00fablicos, privados y al medioambiente.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3d0f0a07b7b3120fd52130e1c427836a\">Al respecto, se promueven acciones para la identificaci\u00f3n y an\u00e1lisis de riesgos en el territorio provincial, y se genera informaci\u00f3n para los tomadores de decisiones a nivel municipal y provincial, una pol\u00edtica que fortalece la prevenci\u00f3n y la eficacia del sistema.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8a1fa400a125d6609cef2bb384311563\">En la jornada se abordar\u00e1, entre otros temas, el cuidado de la vida, los bienes y el medio ambiente en situaciones de emergencias o eventos adversos, acciones para la prevenci\u00f3n y mitigaci\u00f3n de da\u00f1os junto a los organismos del Estado y de la sociedad civil que forman parte del sistema de protecci\u00f3n civil, ejes integrales sobre sistemas de emergencias para que funcionen en forma coordinada, municipios, \u00e1rea de meteorolog\u00eda, sistema de alertas, comunicaci\u00f3n de emergencia, log\u00edstica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El taller, que involucrar\u00e1 a 11 distritos de la regi\u00f3n, se llevar\u00e1 a cabo en la ciudad de Am\u00e9rica, y contar\u00e1 con la presencia de funcionarios provinciales y municipales de las \u00e1reas involucradas.\u00a0 La capacitaci\u00f3n estar\u00e1 a cargo de la directora bonaerense de Fortalecimiento del Sistema de Defensa Civil, Vanesa Misseri, y contar\u00e1 con la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,31,6,9,29,37],"tags":[],"class_list":["post-11809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno-provincial","category-importantes","category-interes-general","category-municipios","category-politica-estado","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2025\/05\/rivadavia-valida.jpg?fit=960%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=11809"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11809\/revisions"}],"predecessor-version":[{"id":11811,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11809\/revisions\/11811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/11810"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=11809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=11809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=11809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}