{"id":12995,"date":"2026-03-18T16:06:27","date_gmt":"2026-03-18T19:06:27","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=12995"},"modified":"2026-03-21T19:38:18","modified_gmt":"2026-03-21T22:38:18","slug":"ameghino-causa-por-abuso-arrestan-a-un-hombre-acusado-por-hechos-ocurridos-cuando-la-victima-tenia-7-anos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-causa-por-abuso-arrestan-a-un-hombre-acusado-por-hechos-ocurridos-cuando-la-victima-tenia-7-anos\/","title":{"rendered":"Ameghino: Causa por abuso: arrestan a un hombre acusado por hechos ocurridos cuando la v\u00edctima ten\u00eda 7 a\u00f1os"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-86f77809783a5102b02a252fcdd6b07f\"><em><strong>El imputado, de entre 40 y 45 a\u00f1os, fue notificado de la medida en las \u00faltimas horas. La denuncia fue realizada por hechos ocurridos cuando la v\u00edctima era menor de edad.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8dc132e1a4d62fc1509afcac666a63d4\">En el d\u00eda de ayer Martes 17\/03, un hombre mayor de edad, de entre 40 y 45 a\u00f1os y conocido en el \u00e1mbito local, habr\u00eda sido detenido bajo la modalidad de arresto domiciliario con monitoreo electr\u00f3nico, en el marco de una causa por abuso que se inici\u00f3 en el a\u00f1o 2021.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-7a2d1607cea5018ed735206824fd9525\">De acuerdo a la informaci\u00f3n recabada, la denuncia fue radicada tras el relato de la v\u00edctima, quien logr\u00f3 manifestar lo sucedido a los 15 a\u00f1os, aunque los hechos se habr\u00edan producido cuando ten\u00eda aproximadamente 7 a\u00f1os. En ese entonces, la menor conviv\u00eda con el acusado y su madre.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-e1850f8cc3b68b9ed19dd1e2907e1920\">Seg\u00fan trascendi\u00f3 a partir del testimonio de un familiar, la joven atraves\u00f3 distintas consecuencias derivadas de la situaci\u00f3n vivida, entre ellas episodios de angustia, ataques de p\u00e1nico y dificultades en su vida cotidiana. Incluso, debi\u00f3 trasladarse junto a su familia a otra ciudad en busca de mayor tranquilidad y para poder retomar sus actividades, en un contexto que describieron como complejo, se\u00f1alando adem\u00e1s situaciones de hostigamiento por parte del acusado.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-06ce65badf7cf2fa629a2ef2a6864a65\">La v\u00edctima, que actualmente tiene 20 a\u00f1os, logr\u00f3 avanzar con el proceso judicial que deriv\u00f3 en la reciente medida dispuesta por la Justicia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d88cab45a286fdb906dd4a48266c3cc6\">En cuanto al estado de la causa, el mismo familiar indic\u00f3 que existe una condena que prev\u00e9 una pena de seis a\u00f1os de prisi\u00f3n. Sin embargo, el acusado permanecer\u00e1 con arresto domiciliario y monitoreo electr\u00f3nico hasta que el Tribunal de Casaci\u00f3n confirme la sentencia. Una vez firme, se prev\u00e9 su traslado a una unidad penitenciaria para el cumplimiento efectivo de la pena.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c21173ffa493722b123722955145f747\">La investigaci\u00f3n contin\u00faar\u00eda bajo intervenci\u00f3n judicial, en un caso que vuelve a poner en agenda la importancia de la denuncia y el acompa\u00f1amiento a las v\u00edctimas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El imputado, de entre 40 y 45 a\u00f1os, fue notificado de la medida en las \u00faltimas horas. La denuncia fue realizada por hechos ocurridos cuando la v\u00edctima era menor de edad. En el d\u00eda de ayer Martes 17\/03, un hombre mayor de edad, de entre 40 y 45 a\u00f1os y conocido en el \u00e1mbito local, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,34,37],"tags":[],"class_list":["post-12995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-policial","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2026\/03\/POLICIALL-VALIDA.png?fit=955%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/12995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=12995"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/12995\/revisions"}],"predecessor-version":[{"id":12997,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/12995\/revisions\/12997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/12996"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=12995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=12995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=12995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}