{"id":1632,"date":"2020-10-04T21:20:21","date_gmt":"2020-10-04T21:20:21","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=1632"},"modified":"2020-10-04T21:20:25","modified_gmt":"2020-10-04T21:20:25","slug":"junin-se-confirmaron-29-nuevos-casos-positivos-de-coronavirus-y-1-fallecimiento","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/junin-se-confirmaron-29-nuevos-casos-positivos-de-coronavirus-y-1-fallecimiento\/","title":{"rendered":"JUNIN:  Se confirmaron 29 nuevos casos positivos de Coronavirus y 1 fallecimiento"},"content":{"rendered":"\n<p>Los casos positivos que se confirmaron este Domingo son 21 mujeres y 8 hombres, de estos, 16 son por contactos estrechos, 3 son trabajadores de la salud y 10 por nexo en estudio. <strong>Hasta el momento Junin cuenta con 454 casos activos.<\/strong><\/p>\n\n\n\n<p>En el d\u00eda de hoy se suman 84 sospechosos de los cuales 10 son contactos estrechos de pacientes COVID+. Las otras personas no tienen antecedentes epidemiol\u00f3gicos, pero de acuerdo a los criterios actuales se los interpreta como casos sospechosos de COVID. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Los casos sospechosos no residentes corresponden a personas de la localidad de Bragado, Los Toldos, Ferre, Pehuaj\u00f3, Teodelina, 25 de Mayo, Laboulaye, Los Toldos y Ascensi\u00f3n. &nbsp;<\/p>\n\n\n\n<p>Por otro lado tambi\u00e9n se inform\u00f3 que  recibieron el alta 17 personas de Jun\u00edn y 4 no residentes que se consideran recuperadas de COVID. Adem\u00e1s, falleci\u00f3 un hombre de 77 a\u00f1os de la ciudad y otro de 80 a\u00f1os de una localidad vecina que se encontraba internado en Jun\u00edn.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta el momento Junin cuenta con 454 casos positivos Covid-19<\/p>\n","protected":false},"author":2,"featured_media":1633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,2,6],"tags":[],"class_list":["post-1632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-destacadas","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/JUNINNNVALIDA.jpg?fit=883%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1632\/revisions"}],"predecessor-version":[{"id":1634,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1632\/revisions\/1634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/1633"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}