{"id":1641,"date":"2020-10-05T01:51:27","date_gmt":"2020-10-05T01:51:27","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=1641"},"modified":"2020-11-02T03:41:29","modified_gmt":"2020-11-02T03:41:29","slug":"deficit-de-precipitaciones-en-octubreque-nos-adelanta-el-s-m-npronostico-de-lluvia-y-temperatura-para-el-mes","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/deficit-de-precipitaciones-en-octubreque-nos-adelanta-el-s-m-npronostico-de-lluvia-y-temperatura-para-el-mes\/","title":{"rendered":"D\u00e9ficit de precipitaciones en Octubre?Que nos adelanta el S.M.N?Pron\u00f3stico de lluvia y temperatura para el mes."},"content":{"rendered":"\n<p>El mes de&nbsp;<strong>octubre inici\u00f3 con un importante ingreso de aire fr\u00edo a la porci\u00f3n central y norte del pa\u00eds<\/strong>. Esta caracter\u00edstica ya generar\u00e1 condiciones de&nbsp;<strong>temperatura inferior a los niveles normales para la \u00e9poca del a\u00f1o<\/strong>, con una importante anomal\u00eda negativa en todo el centro y norte de Argentina,&nbsp;<strong>con la presencia de heladas de variada intensidad especialmente sobre el sur del \u00e1rea pampeana<\/strong>.<\/p>\n\n\n\n<p>Pero en general,&nbsp;<strong>el mes de octubre estar\u00e1 caracterizado por una gran variabilidad t\u00e9rmica<\/strong>, t\u00edpica de la \u00e9poca del a\u00f1o, siendo un mes de transici\u00f3n. As\u00ed como<strong>&nbsp;el comienzo del mes mostrar\u00eda valores de temperatura inferior a lo normal, luego se observar\u00eda un importante incremento t\u00e9rmico<\/strong>, llevando los registros a valores superiores a los promedios t\u00edpicos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"512\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOO.jpg?resize=640%2C512\" alt=\"\" data-id=\"1644\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=1644\" class=\"wp-image-1644\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOO.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOO.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"512\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOOO.jpg?resize=640%2C512\" alt=\"\" data-id=\"1645\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOOO.jpg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=1645\" class=\"wp-image-1645\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOOO.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/LEONARDOOO.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Ya con&nbsp;<strong>el evento La Ni\u00f1a afianzado<\/strong>, las precipitaciones seguir\u00e1n registr\u00e1ndose de manera err\u00e1tica, con fen\u00f3menos aislados tanto en el \u00e1rea como en el tiempo. Esta situaci\u00f3n&nbsp;<strong>volver\u00eda a dejar un d\u00e9ficit de precipitaciones significativo en toda la porci\u00f3n central<\/strong>, mientras que sobre el noreste argentino, aparece un n\u00facleo acotado con una peque\u00f1a franja de lluvias superiores a los promedios en el balance mensual.<\/p>\n\n\n\n<p class=\"has-text-color has-background has-vivid-red-color has-cyan-bluish-gray-background-color\"><strong>Pron\u00f3stico para la primera quincena<\/strong><\/p>\n\n\n\n<p><strong>En la primera semana se destaca la importante entrada de aire fr\u00edo y seco<\/strong>, que proporcionar\u00e1 un muy significativo descenso de las marcas t\u00e9rmicas a nivel generalizado, pero haciendo foco especialmente&nbsp;<strong>sobre el centro y sur de la provincia de&nbsp;<a href=\"https:\/\/www.meteored.com.ar\/tiempo-en-America+Sur-Argentina-Provincia+de+Buenos+Aires-1-6-67-5465.html\">Buenos Aires<\/a>, con heladas de moderada a fuerte intensidad<\/strong>&nbsp;sobre una vasta porci\u00f3n del sur bonaerense.<\/p>\n\n\n\n<p>Del 8 a 14 de octubre,&nbsp;<strong>las precipitaciones se presentar\u00edan por debajo de lo normal en todo el territorio nacional<\/strong>. Si bien se prev\u00e9n algunos eventos de variada intensidad, en general ser\u00e1n aislados y poco significativos, por lo que los acumulados totales se mantendr\u00edan inferiores a los promedios normales.<\/p>\n\n\n\n<p><strong>Las marcas t\u00e9rmicas presentar\u00edan una importante recomposici\u00f3n&nbsp;<\/strong>comparado con los primeros 7 d\u00edas del mes, pero de todas maneras&nbsp;<strong>se mantendr\u00eda la tendencia de valores inferiores a los promedios&nbsp;<\/strong>pr\u00e1cticamente en todo el territorio nacional.<\/p>\n\n\n\n<p class=\"has-text-color has-background has-vivid-red-color has-cyan-bluish-gray-background-color\"><strong>Perspectivas para la segunda mitad de octubre<\/strong><\/p>\n\n\n\n<p>La semana del 15 al 21 de octubre sigue mostrando tendencias de&nbsp;<strong>lluvia inferiores a los promedios en la mayor parte del territorio nacional<\/strong>, lo que indica que las lluvias que podr\u00edan desarrollarse&nbsp;<strong>no ser\u00edan lo suficientemente importantes como para alcanzar los niveles medios<\/strong>. La \u00fanica zona del pa\u00eds que presenta una leve tendencia superior a lo normal, se concentra sobre el extremo noreste del pa\u00eds, abarcando a&nbsp;<a href=\"https:\/\/www.meteored.com.ar\/tiempo-en-America+Sur-Argentina-Corrientes-1-6-67-5472.html\">Corrientes&nbsp;<\/a>y&nbsp;<a href=\"https:\/\/www.meteored.com.ar\/tiempo-en-America+Sur-Argentina-Misiones-1-6-67-5478.html\">Misiones<\/a>.<\/p>\n\n\n\n<p><strong>Las marcas t\u00e9rmicas ya ir\u00edan mostrando un incremento m\u00e1s significativo especialmente sobre el centro del pa\u00eds<\/strong>, con valores cercanos a lo normal e incluso una leve tendencia a valores superiores a los par\u00e1metros t\u00edpicos para la \u00e9poca del a\u00f1o. S\u00f3lo podr\u00eda quedar un peque\u00f1o n\u00facleo con registros levemente inferiores sobre el norte del pa\u00eds.<\/p>\n\n\n\n<p>En cuanto al&nbsp;<strong>\u00faltimo tramo del mes de octubre, es el \u00fanico momento en el que se observan condiciones de lluvia levemente superior a lo normal de manera casi generalizada<\/strong>, ya que tanto en la porci\u00f3n central como en el norte argentino se podr\u00edan desarrollar precipitaciones con caudales superiores a los promedios para ese per\u00edodo.<\/p>\n\n\n\n<p>Mientras tanto,&nbsp;<strong>las marcas t\u00e9rmicas volver\u00edan a presentarse superiores al promedio en todo el pa\u00eds<\/strong>, especialmente sobre la franja norte del territorio nacional, donde se observar\u00edan los n\u00facleos m\u00e1s c\u00e1lidos, y con los valores m\u00e1s alejados de los promedios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leonardo De Benedictis: Meteor\u00f3logo pronostica escasez de lluvias y temperaturas variadas.<\/p>\n","protected":false},"author":2,"featured_media":1643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2,6],"tags":[],"class_list":["post-1641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/VALIDO.jpg?fit=711%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1641\/revisions"}],"predecessor-version":[{"id":1678,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1641\/revisions\/1678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/1643"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}