{"id":1972,"date":"2020-10-24T22:48:05","date_gmt":"2020-10-24T22:48:05","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=1972"},"modified":"2020-10-25T23:59:37","modified_gmt":"2020-10-25T23:59:37","slug":"covid-19-ameghino-arrojo-un-nuevo-positivo","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/municipios\/florentino-ameghino\/covid-19-ameghino-arrojo-un-nuevo-positivo\/","title":{"rendered":"COVID-19. AMEGHINO ARROJ\u00d3 UN NUEVO  POSITIVO"},"content":{"rendered":"\n<p>Segun informe de la Direccion de salud se recibieron hoy Sabado dos de los hisopados pendientes arrojando uno de ellos resultado POSITIVO.<\/p>\n\n\n\n<p>Se trata de un paciente de sexo femenino de Ameghino quien se encuentra aislada desde el dia que fue hisopada por presentar sitomas leves.<\/p>\n\n\n\n<p>Al dia de hoy se registran dos casos activos,  dos recuperados y ocho casos sospechosos.<\/p>\n\n\n\n<p>En tanto 114 personas se encuentran aisladas cumpliendo la cuarentena preventiva, siendo todos monitoreados por el equipo de salud.Ninguno ha presentado sintomas hasta el momento.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Salud de Florentino Ameghino informa:<br>En relaci\u00f3n a los estudios pendientes de casos sospechosos de COVID-19, uno (1) arroj\u00f3 resultado negativo y uno (1) positivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"691\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-24-at-19.34.14-948x1024.jpeg?resize=640%2C691\" alt=\"\" class=\"wp-image-1974\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-24-at-19.34.14.jpeg?resize=948%2C1024&amp;ssl=1 948w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-24-at-19.34.14.jpeg?resize=278%2C300&amp;ssl=1 278w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-24-at-19.34.14.jpeg?resize=768%2C830&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-24-at-19.34.14.jpeg?w=1185&amp;ssl=1 1185w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una paciente de Ameghino que present\u00f3 sintomas leves.<\/p>\n","protected":false},"author":2,"featured_media":1975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,24],"tags":[],"class_list":["post-1972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-florentino-ameghino"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/COVIDVALIDO.jpg?fit=748%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1972"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1972\/revisions"}],"predecessor-version":[{"id":1976,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1972\/revisions\/1976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/1975"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}