{"id":2047,"date":"2020-10-29T17:03:32","date_gmt":"2020-10-29T17:03:32","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2047"},"modified":"2020-10-29T22:13:36","modified_gmt":"2020-10-29T22:13:36","slug":"c-tejedor-se-amplia-el-horario-de-bares-y-restaurantes","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/c-tejedor-se-amplia-el-horario-de-bares-y-restaurantes\/","title":{"rendered":"C.TEJEDOR: SE AMPL\u00cdA EL HORARIO DE BARES Y RESTAURANTES."},"content":{"rendered":"\n<p>El anuncio se hizo este mediod\u00eda desde la municipalidad por medio de la Secretar\u00eda de prensa, <strong>\u00ablos bares y restaurantes quedan habilitados para abrir hasta las 2 de la ma\u00f1ana de Lunes a Domingos\u00bb.<\/strong><\/p>\n\n\n\n<p>Esta desicion se toma mirando el <strong>\u00abdecrecimiento\u00bb<\/strong> que viene teniendo el Distrito en casos positivos Covid-19.-manifest\u00f3 un alto funcionario del municipio &#8211; en un acuerdo elaborado entre el ejecutivo, el \u00e1rea de salud y el comit\u00e9 de crisis.<\/p>\n\n\n\n<p>Como en todo momento estaremos atentos a como se va desarrollando esta flexibilizaci\u00f3n, <strong>si hubiera alg\u00fan \u00edndice de crecimientos de casos, no dudaremos en sentarnos nuevamente a evaluar la situaci\u00f3n<\/strong>-manifest\u00f3-<\/p>\n\n\n\n<p><strong>Hoy en el distrito de Tejedor cuentan con 3 casos activos y 5 sospechosos, habiendo amentado el fallecimiento de 2 personas por Covid-19<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1-1024x1024.jpeg?resize=375%2C375\" alt=\"\" class=\"wp-image-2050\" width=\"375\" height=\"375\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-29-at-08.43.59-1.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El acuerdo se llevo a cabo mirando la situaci\u00f3n Covid en el Distrito.<\/p>\n","protected":false},"author":2,"featured_media":2056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,28,2],"tags":[],"class_list":["post-2047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carlos-tejedor","category-salud-covid19","category-destacadas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/10\/BARES-VALIDO111222-1.jpeg?fit=875%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2047"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2047\/revisions"}],"predecessor-version":[{"id":2051,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2047\/revisions\/2051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2056"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}