{"id":2115,"date":"2020-11-05T14:29:03","date_gmt":"2020-11-05T14:29:03","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2115"},"modified":"2020-11-08T16:08:02","modified_gmt":"2020-11-08T16:08:02","slug":"por-que-ameghino-actua-como-fase-5-estando-en-fase-4","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/politica-estado\/gobierno-provincial\/por-que-ameghino-actua-como-fase-5-estando-en-fase-4\/","title":{"rendered":"\u00bfPOR QUE AMEGHINO ACTUA COMO FASE 5 ESTANDO EN FASE 4?"},"content":{"rendered":"\n<p>Seg\u00fan informe oficial del Gobierno de la Pcia de Buenos Aires el Distrito de Ameghino inici\u00f3 el mes de Noviembre con una baja en su fase- <strong>de 5 baj\u00f3 a 4-<\/strong> si bien esto significa que debieron haber efectuado algunos cambios desde el Municipio, relacionados a actividades que deber\u00edan haber dejado de funcionar y que se establecen seg\u00fan protocolo Covid-19,  hasta el momento no se ha anunciado ni mencionado  ninguna modificaci\u00f3n  al respecto.<\/p>\n\n\n\n<p>Despu\u00e9s de haber contado Ameghino con mas de 10 casos positivos Covid-19  y teniendo en cuenta que si mas del 0,10% de la poblaci\u00f3n esta afectada el protocolo indica bajar una fase, la expectativa comenz\u00f3 a surgir por parte de la ciudadan\u00eda, al no realizarse anuncio alguno a nivel local.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ciudad-2.jpg?resize=362%2C270\" alt=\"\" class=\"wp-image-2117\" width=\"362\" height=\"270\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ciudad-2.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ciudad-2.jpg?resize=300%2C224&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ciudad-2.jpg?resize=768%2C574&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ciudad-2.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 362px) 100vw, 362px\" \/><\/figure><\/div>\n\n\n\n<p>As\u00ed es como &#8211; seg\u00fan fuentes consultadas por este medio- sobre el accionar en este aspecto y poner claridad al tema, nos confirmaban que desde el gobierno provincial s\u00ed se remiti\u00f3 este cambio al municipio anunciando la fase 4 desde el primer dia de Noviembre cuando ya hab\u00eda bajado la cantidad de positivos y agregando  que <strong>se cuentan como casos de Ameghino a todas aquellas personas que tienen domicilio en el lugar, est\u00e1n afectados por la enfermedad  y no  radican en el mismo, <\/strong>adem\u00e1s se recibi\u00f3 un informe de situaci\u00f3n local  en donde se comprueba que los casos que se dieron fueron provenientes de contactos estrechos.<\/p>\n\n\n\n<p>Tal como se encuentra hoy la situaci\u00f3n Covid-19 en el Distrito de Ameghino \u00ab<strong>con 4 activos- 11 casos recuperados y 4 sospechosos<\/strong>\u00bb   <strong>Ameghino seguir\u00eda actuando en fase 5<\/strong>, <strong>\u00abya que los estados  se actualizan una ves al mes en la Provincia <\/strong>y esa es la raz\u00f3n por la cual hoy formalmente en el protocolo Provincial figura Distrito en fase 4 pero con comportamiento de fase 5.<\/p>\n\n\n\n<p>Es de esperar que &#8211; si la situaci\u00f3n sigue con tendencia a la baja- en Diciembre ya se encuentre nuevamente en la fase anterior en el registro Provincial.<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan fuentes consultadas, formalmente es fase 4. Aunque la realidad es de 5<\/p>\n","protected":false},"author":2,"featured_media":2116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,24,11],"tags":[],"class_list":["post-2115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-florentino-ameghino","category-gobierno-provincial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ameghino-3.jpg?fit=726%2C485&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2115"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2115\/revisions"}],"predecessor-version":[{"id":2120,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2115\/revisions\/2120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2116"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}