{"id":2130,"date":"2020-11-07T19:40:02","date_gmt":"2020-11-07T19:40:02","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2130"},"modified":"2020-11-12T01:31:55","modified_gmt":"2020-11-12T01:31:55","slug":"entre-15-y-17-millones-de-visones-seran-sacrificados-por-mutacion-de-coronavirus","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/entre-15-y-17-millones-de-visones-seran-sacrificados-por-mutacion-de-coronavirus\/","title":{"rendered":"Entre 15 y 17 millones de visones ser\u00e1n sacrificados por mutaci\u00f3n de coronavirus"},"content":{"rendered":"\n<p>Seg\u00fan las autoridades &#8211; podr\u00edan representar un riesgo para futuras vacunas. En un solo d\u00eda se sacrificaron m\u00e1s de 1,2 millones de animales.<\/p>\n\n\n\n<p>Dinamarca, primer productor mundial de piel de vis\u00f3n,&nbsp;<strong>sacrificar\u00e1 alrededor de 15 millones de ejemplares criados en su territorio a causa de una mutaci\u00f3n de la covid-19 que ya habr\u00eda pasado a 12 personas<\/strong>, lo que amenaza la eficacia de una futura vacuna para el humano.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/VISONES2.jpg?resize=398%2C226\" alt=\"\" class=\"wp-image-2132\" width=\"398\" height=\"226\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/VISONES2.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/VISONES2.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/VISONES2.jpg?resize=768%2C438&amp;ssl=1 768w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/><\/figure><\/div>\n\n\n\n<p><strong>\u00abEl virus mutado a trav\u00e9s de los&nbsp;visones&nbsp;podr\u00eda representar un riesgo de que futuras vacunas<\/strong>&nbsp;(contra el covid-19) no funcionen como deber\u00eda\u00bb, declar\u00f3 la primera ministra Mette Frederiksen, durante una rueda de prensa con funcionarios de salud.&nbsp;<\/p>\n\n\n\n<p><strong>\u00abHay que sacrificar a todos los&nbsp;visones<\/strong>\u00ab, a\u00f1adi\u00f3,&nbsp;<strong>lo que representa entre 15 y 17 millones de animales,<\/strong>&nbsp;precis\u00f3.<\/p>\n\n\n\n<p><strong>La mutaci\u00f3n de un virus es normal, y una mutaci\u00f3n no significa que se comportar\u00e1 de manera diferente,<\/strong>&nbsp;seg\u00fan los cient\u00edficos. Adem\u00e1s, determinar las consecuencias concretas de una mutaci\u00f3n es complejo.<\/p>\n\n\n\n<p>Pero aunque esta mutaci\u00f3n no agrava las complicaciones causadas por el coronavirus en el ser humano, l<strong>as autoridades danesas consideran que se&nbsp;caracteriza por una menor eficacia de los anticuerpos humanos<\/strong>, lo que amenaza el desarrollo de una vacuna de coronavirus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doce personas en Dinamarca ya fueron infectadas con el virus mutado, transmitido por los visones mam\u00edferos<\/p>\n","protected":false},"author":2,"featured_media":2131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,6],"tags":[],"class_list":["post-2130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/VISONES-1-valida.jpg?fit=888%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2130"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2130\/revisions"}],"predecessor-version":[{"id":2159,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2130\/revisions\/2159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2131"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}