{"id":2171,"date":"2020-11-10T20:48:31","date_gmt":"2020-11-10T20:48:31","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2171"},"modified":"2020-11-14T17:48:22","modified_gmt":"2020-11-14T17:48:22","slug":"anses-ameghino-cerrado-por-aislamiento","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/municipios\/florentino-ameghino\/anses-ameghino-cerrado-por-aislamiento\/","title":{"rendered":"ANSES AMEGHINO CERRADO POR AISLAMIENTO"},"content":{"rendered":"\n<p>La oficina de Anses Ameghino permanecera cerrada al publico hasta el Martes 17 de Noviembre.<\/p>\n\n\n\n<p>La desicion fue tomada debido al <strong>estado de Aislamiento Social y Preventivo en que se encuentra todo el personal,<\/strong> despu\u00e9s de haberse confirmado un caso positivo de una de las personas que se desempe\u00f1a como auxiliar en el lugar.<\/p>\n\n\n\n<p>La Directora de Anses Ameghino Rosario Medialdea-desde su aislamiento- inform\u00f3 que aquellas personas que necesiten comunicarse lo hagan a trav\u00e9s del Mail: <strong>oficinaameghino@anses.gov.ar o bien iniciando una atenci\u00f3n virtual desde su celular o computadora entrando a www.anses.gob.ar<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La oficina de Anses Ameghino permanecera cerrada al publico hasta el Martes 17 de Noviembre. La desicion fue tomada debido al estado de Aislamiento Social y Preventivo en que se encuentra todo el personal, despu\u00e9s de haberse confirmado un caso positivo de una de las personas que se desempe\u00f1a como auxiliar en el lugar. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,24],"tags":[],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-florentino-ameghino"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/11\/ANSES-1.jpg?fit=600%2C415&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"predecessor-version":[{"id":2173,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2171\/revisions\/2173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2172"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}