{"id":2488,"date":"2020-12-13T15:25:07","date_gmt":"2020-12-13T15:25:07","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2488"},"modified":"2020-12-15T09:44:58","modified_gmt":"2020-12-15T09:44:58","slug":"ameghino-ganadores-de-la-segunda-gran-rifa-de-bomberos-voluntarios","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-ganadores-de-la-segunda-gran-rifa-de-bomberos-voluntarios\/","title":{"rendered":"AMEGHINO:         GANADORES DE LA SEGUNDA GRAN RIFA DE BOMBEROS VOLUNTARIOS."},"content":{"rendered":"\n<p> De acuerdo al sorteo realizado por la loter\u00eda de la provincia de Bs As el d\u00eda 12\/12\/2020 correspondiente al sorteo mensual, la Instituci\u00f3n inform\u00f3 los n\u00fameros favorecidos y ganadores.<\/p>\n\n\n\n<p><strong>Primer premio <\/strong>N\u00b0 061 un smart TV 50&#8243; Noblex ganador: Sergio Sarmiento <strong>Segundo premio<\/strong>  N\u00b0 666 una bicicleta ganadora: Lidia Laxagueborde<\/p>\n\n\n\n<p><strong>Tercer premio<\/strong>  N\u00b0 638 un horno Atma, ganadora: Gabriela S\u00e1nchez<\/p>\n\n\n\n<p> <strong>Cuarto premio<\/strong>  N\u00b0 227 Mesa + 4 sillas, ganador Luis Haylan <\/p>\n\n\n\n<p><strong>Quinto premio<\/strong>  N\u00b0 692 Una pava el\u00e9ctrica, ganador Carlos Alb\u00edn.<\/p>\n\n\n\n<p>El cuerpo activo y comisi\u00f3n directiva de bombero felicita a todos los ganadores y agradece a  la comunidad por la constante colaboraci\u00f3n, recordando que el pr\u00f3ximo sorteo es el ultimo  y se llevar\u00e1 a cabo el d\u00eda 23\/12\/2020 por loter\u00eda nocturna de la provincia de BS AS donde el primer premio es un AUTOM\u00d3VIL 0KM, segundo premio un ciclomotor Mondial 110, tercer premio 1 PC Notebook y 7 importantes premios m\u00e1s. La rifa debe estar cancelada en su totalidad el d\u00eda 22\/12 para acceder al premio. <\/p>\n\n\n\n<p>Adem\u00e1s la instituci\u00f3n recuerda &#8211; a trav\u00e9s de este medio- que  juntamente con otras pares del distrito tienen en venta el bingo on line que se llevar\u00e1 a cabo el domingo 20, cuyo costo es de  $300 .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confirmado el ultimo sorteo ser\u00e1 el 23 de Diciembre.<\/p>\n","protected":false},"author":2,"featured_media":2489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6],"tags":[],"class_list":["post-2488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/BOMBROS-2valida.jpg?fit=1032%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2488"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2488\/revisions"}],"predecessor-version":[{"id":2491,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2488\/revisions\/2491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2489"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}