{"id":2508,"date":"2020-12-15T23:54:04","date_gmt":"2020-12-15T23:54:04","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2508"},"modified":"2020-12-15T23:54:08","modified_gmt":"2020-12-15T23:54:08","slug":"covid-19-gral-pinto-se-registra-otro-dia-con-aumentos-de-positivos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/covid-19-gral-pinto-se-registra-otro-dia-con-aumentos-de-positivos\/","title":{"rendered":"Covid-19 Gral Pinto.               Se registra otro dia con aumentos de  positivos."},"content":{"rendered":"\n<p>Desde el Municipio dieron a conocer a trav\u00e9s de informe de prensa el aumento que se viene dando en los \u00faltimos d\u00edas de casos positivos C0vid-19.<\/p>\n\n\n\n<p> En el dia de la fecha 15\/12\/2020 <strong>se registraron 10 nuevos casos activos y 5 casos mas sospechosos <\/strong>que fueron hisopados y se aguarda resultado.<\/p>\n\n\n\n<p>En tanto las autoridades de salud manifestaron que hay tres pacientes internados en el Hospital Pintense y seis se encuentran alojados en el centro de internacion Extrahospitalaria, el resto de los contagiados  se encuentran cumpliendo el aislamiento en sus domicilios.<\/p>\n\n\n\n<p><strong>Hasta el momento el Distrito cuenta con 300 casos totales de los cuales 190 pertenecen a la ciudad cabecera, 61 a Coronel Granada, 43 a Germania y 6 a Iriarte<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/PINTO-HOYYY.jpg?resize=406%2C444\" alt=\"\" class=\"wp-image-2509\" width=\"406\" height=\"444\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/PINTO-HOYYY.jpg?w=526&amp;ssl=1 526w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/PINTO-HOYYY.jpg?resize=274%2C300&amp;ssl=1 274w\" sizes=\"auto, (max-width: 406px) 100vw, 406px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las ultimas semanas no son alentadoras en cuanto a resultados de hisopados.<\/p>\n","protected":false},"author":2,"featured_media":2510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-2508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/PINTO-VALIDA.jpg?fit=1033%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2508"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2508\/revisions"}],"predecessor-version":[{"id":2511,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2508\/revisions\/2511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2510"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}