{"id":2567,"date":"2020-12-22T13:58:33","date_gmt":"2020-12-22T13:58:33","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2567"},"modified":"2020-12-22T13:59:38","modified_gmt":"2020-12-22T13:59:38","slug":"rural-fuerte-desencuentro-entre-uatre-y-entidades-patronales-por-el-bono-de-fin-de-ano","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/rural-fuerte-desencuentro-entre-uatre-y-entidades-patronales-por-el-bono-de-fin-de-ano\/","title":{"rendered":"Rural.                                FUERTE DESENCUENTRO ENTRE UATRE Y ENTIDADES PATRONALES POR EL BONO DE FIN DE A\u00d1O."},"content":{"rendered":"\n<p>Desde el gremio que nuclea a los empleados del campo manifestaron d\u00edas pasados su disconformidad con las organizaciones patronales por haber  negado el pedido, por \u00fanica vez, de otorgar a los trabajadores $ 15.000 como Bono de Fin de A\u00f1o.<\/p>\n\n\n\n<p>Ayer Lunes y luego de una reuni\u00f3n frustrada con las entidades gremiales del campo en donde ped\u00edan un bono de $15.000 para sus asociados,\u00a0<strong>la Uni\u00f3n Argentina de Trabajadores Rurales y Estibadores (Uatre) resolvi\u00f3 aceptar una propuesta, del Gobierno, de un bono de $10.000,<\/strong>\u00a0a pagar en tres cuotas mensuales y por \u00fanica vez. A ese bono se lleg\u00f3 tras una votaci\u00f3n en el \u00e1mbito de la Comisi\u00f3n Nacional de Trabajo Agrario (CNTA) despu\u00e9s de un rechazo de organizaciones del sector.<\/p>\n\n\n\n<p>A pesar del bono conseguido,\u00a0<strong>la Uatre se\u00f1al\u00f3 que contin\u00faa en \u00abestado de alerta y movilizaci\u00f3n porque el bono aprobado est\u00e1 muy lejos de constituir el reconocimiento a la labor que tuvieron los trabajadores rurales en todos estos meses de pandemia\u00bb.<\/strong><\/p>\n\n\n\n<p>\u00abSi esta es la actitud del sector empresario, las decisiones gremiales ser\u00e1n a\u00fan m\u00e1s graves. Es una verg\u00fcenza escuchar argumentos que solo se sustentan en una ideolog\u00eda elitista que considera a los trabajadores como personas de segunda categor\u00eda. Lamentamos la grosera insensibilidad en los grandes empresarios del campo argentino\u00bb, dijeron luego del acuerdo.<\/p>\n\n\n\n<p>En un encuentro en la CNTA,\u00a0<strong>las entidades empresariales se mantuvieron en la negativa, por lo que se dispuso convocar a votaci\u00f3n, donde los dos votos del Estado fueron clave para la resoluci\u00f3n del conflicto.\u00a0<\/strong>El gremio se impuso cuatro votos a dos de la parte empresarial, que en esta oportunidad pertenec\u00edan a CRA y Coninagro.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/UATRE-1.jpg?resize=349%2C196\" alt=\"\" class=\"wp-image-2571\" width=\"349\" height=\"196\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/UATRE-1.jpg?w=829&amp;ssl=1 829w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/UATRE-1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/UATRE-1.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 349px) 100vw, 349px\" \/><figcaption>Jos\u00e9 Voytenco Sec. Gral Uatre <\/figcaption><\/figure><\/div>\n\n\n\n<p>\u00abN<strong><em>uestros trabajadores fueron declarados como esenciales y han cumplido con su trabajo durante todo el a\u00f1o, a\u00fan arriesgando su salud y poni\u00e9ndole el cuerpo a la pandemia\u00bb.<\/em><\/strong><\/p>\n\n\n\n<p>Horas previas a la reuni\u00f3n, en conferencia de prensa virtual, el secretario general del gremio, Jos\u00e9 Voytenco, dijo que los trabajadores estaban esperando una respuesta.\u00a0<strong>\u00abLa bonanza del sector debe estar traducida en el bolsillo del trabajador rural. Estamos en alerta y movilizaci\u00f3n permanente.\u00a0<\/strong>Si luego de la reuni\u00f3n no se logra un acuerdo, vamos a juntarnos en el gremio para definir c\u00f3mo vamos a continuar.\u00a0<strong>Espero que prime la cordura empresarial y tener una respuesta concreta. Tenemos esperanza y fe que hoy podamos consensuar\u00bb,<\/strong>\u00a0indic\u00f3.<\/p>\n\n\n\n<p>Asimismo, Voytenco cont\u00f3 que la \u00fanica organizaci\u00f3n empresarial que hab\u00eda avalado su pedido fue la\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/tema\/federacion-agraria-argentina-faa-tid65696\">Federaci\u00f3n Agraria Argentina (FAA),\u00a0<\/a>quien hab\u00eda hecho una contrapropuesta de $12.000, pero que el resto tuvo una actitud negativa: \u00abLa \u00fanica que est\u00e1 respaldando el planteo gremial es FAA. Las otras tres entidades no apoyaron la propuesta\u00bb.<\/p>\n\n\n\n<p>Para el gremio, a un productor agropecuario de cualquier actividad del campo $15.000 no lo afecta en nada. \u00abSolo equivalen a un cambio de aceite y filtro de una camioneta, o lo que le queda a un productor por 700 kilos de soja o 100 kilos de ternera, o por la venta de seis cajones de pollo o un tercio de lo que produce una planta de manzana. Ning\u00fan productor va a hacer temblar su econom\u00eda por este bono. El lazo est\u00e1 hecho de buen tiento pero se puede cortar\u00bb, reclamaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente los trabajadores rurales tendr\u00e1n un bono de $10.000 acordado con el Gobierno sin el aval de las entidades <\/p>\n","protected":false},"author":2,"featured_media":2570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2,10,33],"tags":[],"class_list":["post-2567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-gobierno","category-rural"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/12\/UATRE3valida-1.png?fit=1008%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2567"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2567\/revisions"}],"predecessor-version":[{"id":2572,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2567\/revisions\/2572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2570"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}