{"id":2843,"date":"2021-01-21T15:07:22","date_gmt":"2021-01-21T15:07:22","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2843"},"modified":"2021-01-22T18:16:46","modified_gmt":"2021-01-22T18:16:46","slug":"tres-algarrobos-un-hombre-fue-encontrado-sin-vida-esta-manana","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/tres-algarrobos-un-hombre-fue-encontrado-sin-vida-esta-manana\/","title":{"rendered":"Tres Algarrobos.                     Un hombre fue encontrado sin vida esta ma\u00f1ana."},"content":{"rendered":"\n<p>UN SUICIDIO TERMINO CON LA VIDA DE UN HOMBRE DE CUENCA.<\/p>\n\n\n\n<p>El hecho sucedi\u00f3 esta madrugada- seg\u00fan las primeras informaciones- la polic\u00eda estima que se tratar\u00eda de un suicidio.<\/p>\n\n\n\n<p>Un ciudadano de sexo Masculino de aproximadamente 50 a\u00f1os fue encontrado sin vida en la tumba de su padre  en el \u00abCementerio Parque\u00bb que esta ubicado sobre el Acceso Padre Inocencio en el ingreso a la localidad.<\/p>\n\n\n\n<p>Seg\u00fan pudo conocerse hasta el momento, el hombre vendr\u00eda atravesando un dif\u00edcil momento personal que lo habr\u00eda llevado a tomar la decisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN SUICIDIO TERMINO CON LA VIDA DE UN HOMBRE DE CUENCA. El hecho sucedi\u00f3 esta madrugada- seg\u00fan las primeras informaciones- la polic\u00eda estima que se tratar\u00eda de un suicidio. Un ciudadano de sexo Masculino de aproximadamente 50 a\u00f1os fue encontrado sin vida en la tumba de su padre en el \u00abCementerio Parque\u00bb que esta ubicado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,31,6],"tags":[],"class_list":["post-2843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carlos-tejedor","category-importantes","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/01\/CEMENTERIOvalido.jpg?fit=889%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2843"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2843\/revisions"}],"predecessor-version":[{"id":2846,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2843\/revisions\/2846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2844"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}