{"id":2952,"date":"2021-02-03T00:08:20","date_gmt":"2021-02-03T00:08:20","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=2952"},"modified":"2021-02-26T01:04:09","modified_gmt":"2021-02-26T01:04:09","slug":"tejedor-el-verano-atr-fue-un-acompanamiento-para-los-alumnos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/deportes\/tejedor-el-verano-atr-fue-un-acompanamiento-para-los-alumnos\/","title":{"rendered":"Tejedor:                                       El VERANO ATR FUE UN ACOMPA\u00d1AMIENTO PARA LOS ALUMNOS"},"content":{"rendered":"\n<p>-UN PROGRAMA PROVINCIAL QUE VINO A CUBRIR UNA NECESIDAD DE INTERACCION ENTRE DOCENTES Y ALUMNOS-<strong> FRANCO CRESPO<\/strong> COORDINADOR EN C. TEJEDOR-<\/p>\n\n\n\n<p>Durante el mes de enero se desarroll\u00f3 en todos los municipios de la Pcia de Bs As el <strong>\u201cVerano ATR\u201d<\/strong> destinado para ense\u00f1ar recreando a partir de juegos y actividades que promueven el aprendizaje, el cuidado del cuerpo y la recreaci\u00f3n.<\/p>\n\n\n\n<p>En una charla que mantuvimos con Franco Crespo el coordinador del programa en Tejedor nos manifest\u00f3 que<strong> fue un acompa\u00f1amiento para alumnos que se hab\u00edan desvinculado de la escuela <\/strong>debido a la pandemia y hab\u00edan trabajado con los ATR que son los docentes en formaci\u00f3n durante el ciclo lectivo 2020 y se les dio continuidad en enero, prepar\u00e1ndolos para el ciclo lectivo 2021.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0021-505x1024.jpg?resize=505%2C1024\" alt=\"\" data-id=\"2954\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=2954\" class=\"wp-image-2954\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0021.jpg?resize=505%2C1024&amp;ssl=1 505w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0021.jpg?resize=148%2C300&amp;ssl=1 148w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0021.jpg?w=540&amp;ssl=1 540w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024-1024x768.jpg?resize=640%2C480\" alt=\"\" data-id=\"2955\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=2955\" class=\"wp-image-2955\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg?resize=136%2C102&amp;ssl=1 136w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/IMG-20210202-WA0024.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\">DISTINTAS ACTIVIDADES DE VERANO ATR<\/figcaption><\/figure>\n\n\n\n<p><strong>-No fue un programa exclusivo, esto hizo que se incorporaran muchos alumnos que estaban en trayectorias m\u00e1s avanzadas-.<\/strong><\/p>\n\n\n\n<p>Las actividades fueron recreativas, culturales, se trabaj\u00f3 con contenidos priorizados, un abanico de oportunidades muy grandes con diferentes aprendizajes.<\/p>\n\n\n\n<p>No solo fue aprendizaje \u2013nos asegur\u00f3 Franco Crespo. sino que <strong>vino a cumplir con el reinicio de clases presenciales que los alumnos no tuvieron o fueron muy escasas el pasado a\u00f1o <\/strong>y eso se not\u00f3, los alumnos necesitaban de ese v\u00ednculo entre compa\u00f1eros y docentes, ese contacto es irremplazable \u2013 asegur\u00f3 en la nota- agregando que se pudo realizar cumpliendo un protocolo con medidas de seguridad e higiene aun con una cantidad de 180 inscriptos y no existi\u00f3 ning\u00fan contagio Covid-19 siendo las edades de entre 6 a 18 a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO-2.jpg?resize=640%2C360\" alt=\"\" data-id=\"2956\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=2956\" class=\"wp-image-2956\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO-2.jpg?w=889&amp;ssl=1 889w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO-2.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO-2.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO.jpg?resize=640%2C360\" alt=\"\" data-id=\"2957\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO.jpg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=2957\" class=\"wp-image-2957\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO.jpg?w=889&amp;ssl=1 889w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/ATR-VALIDO.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\">Actividades de Verano <\/figcaption><\/figure>\n\n\n\n<p>El coordinador destac\u00f3 el trabajo que hicieron el personal docente, directivos, coordinadores, las autoridades municipales quienes ofrecieron todas las instalaciones en muy buenas condiciones para desarrollar el programa incluido los espejos de agua que -asegur\u00f3- no es com\u00fan encontrar en cada pueblo del distrito una pileta como s\u00ed las tiene Tejedor, aclarando que  cada localidad tiene un natatorio municipal.<\/p>\n\n\n\n<p>Si bien ya cerr\u00f3 el Verano ATR ahora -nos manifestaba- a trav\u00e9s de la direcci\u00f3n de deportes a cargo de la profesora Ana Clara Issa \u2013 seguimos con la colonia municipal durante todo febrero, que ya deja de ser un programa provincial para dirigirlo a nivel distrital- &nbsp;incorporando actividades recreativas acu\u00e1ticas y l\u00fadicas con el objetivo de que no quede un mes vac\u00edo de actividades antes de comienzo de clases.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franco Crespo Coordinador Distrital \u00abEste programa vino a suplir la escasa presencialidad en la escuela del 2020\u00bb<\/p>\n","protected":false},"author":2,"featured_media":2953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,8,11],"tags":[],"class_list":["post-2952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carlos-tejedor","category-deportes","category-gobierno-provincial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/FRANCO-CRESPO-VALIDA.jpg?fit=889%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2952"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2952\/revisions"}],"predecessor-version":[{"id":2976,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2952\/revisions\/2976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/2953"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}