{"id":3031,"date":"2021-02-16T11:59:04","date_gmt":"2021-02-16T11:59:04","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3031"},"modified":"2021-02-26T01:01:11","modified_gmt":"2021-02-26T01:01:11","slug":"carnaval-2021-en-argentina-origen-significado-y-por-que-se-celebra","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/carnaval-2021-en-argentina-origen-significado-y-por-que-se-celebra\/","title":{"rendered":"Carnaval 2021 en Argentina: Origen, Significado y Por qu\u00e9 se celebra"},"content":{"rendered":"\n<p>Lunes 15 y martes 16 de febrero&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/argentina.as.com\/argentina\/2020\/11\/28\/actualidad\/1606571463_533744.html\" target=\"_blank\">son feriados nacionales en Argentina<\/a>&nbsp;porque se celebra el Carnaval, como cada a\u00f1o desde 2010.<\/p>\n\n\n\n<p><strong>.<\/strong>&nbsp;En un principio era una celebraci\u00f3n pagana pero de origen cristiano, vinculada a los d\u00edas previos a \u00ablimpiar la carne\u00bb, que desemboca en la prohibici\u00f3n religiosa de consumirla durante los cuarenta d\u00edas que dura la cuaresma.<\/p>\n\n\n\n<p>Esta festividad era distinta seg\u00fan los sectores sociales: en tiempos de la Colonia, los sectores populares participaban en los bailes de m\u00e1scaras que se realizaban en el teatro de La Rancher\u00eda, mientras que los sectores pudientes lo hac\u00edan en la Casa de Comedias.<\/p>\n\n\n\n<p>Como en la actualidad, el carnaval tambi\u00e9n ocup\u00f3 el espacio p\u00fablico:&nbsp;<strong>bailes y juegos con agua inundaron las calles,<\/strong>&nbsp;lo que eran \u00abcostumbres b\u00e1rbaras\u00bb para las clases altas, que se opon\u00edan al festejo.<\/p>\n\n\n\n<p>Entre 1829 y 1852 -durante la primera y segunda gobernaci\u00f3n de Juan Manuel de Rosas- se censur\u00f3 por decreto hasta 1854, a\u00f1o en que el gobierno de Buenos Aires autoriz\u00f3 la realizaci\u00f3n de bailes de m\u00e1scaras y juegos de agua nuevamente.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/comparsa_los_diablos_y_las_noches_agn_11978-1024x752.jpg?resize=423%2C310\" alt=\"\" class=\"wp-image-3033\" width=\"423\" height=\"310\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/comparsa_los_diablos_y_las_noches_agn_11978.jpg?resize=1024%2C752&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/comparsa_los_diablos_y_las_noches_agn_11978.jpg?resize=300%2C220&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/comparsa_los_diablos_y_las_noches_agn_11978.jpg?resize=768%2C564&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/comparsa_los_diablos_y_las_noches_agn_11978.jpg?w=1090&amp;ssl=1 1090w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><\/figure><\/div>\n\n\n\n<p>En 1869, durante la presidencia de Domingo Faustino Sarmiento, se promueve el primer corso oficial de la Ciudad de Buenos Aires. Fue el propio Sarmiento quien, tras un viaje por Montevideo, R\u00edo de Janeiro, Francia, Espa\u00f1a, Argelia, Italia, Alemania, Suiza, Inglaterra, Estados Unidos, Canad\u00e1 y Cuba, queda maravillado&nbsp;<strong>por la idea del anonimato de los disfraces como forma de borrar, por un instante, la desigualdad de clases sociales.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"202\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/carnaval_1900.jpg?resize=640%2C202\" alt=\"\" class=\"wp-image-3034\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/carnaval_1900.jpg?w=696&amp;ssl=1 696w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/carnaval_1900.jpg?resize=300%2C95&amp;ssl=1 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>En 1976, durante la dictadura c\u00edvico-militar, se elimin\u00f3 al carnaval del calendario oficial de festejos y se detuvieron sus manifestaciones callejeras. En 1983, desde la vuelta a la democracia, regres\u00f3 el festejo, a pesar de que s\u00f3lo hab\u00edan sobrevivido una decena de murgas.<\/p>\n\n\n\n<p><strong>En el a\u00f1o 2010 se restituyeron oficialmente los feriados nacionales del lunes y martes de carnaval<\/strong>&nbsp;y regresaron los festejos masivos en las calles de todo el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este festejo fue instalado en el pa\u00eds por los espa\u00f1oles en el siglo XVIII y fue mutando a murgas en el XX. <\/p>\n","protected":false},"author":2,"featured_media":3032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,6],"tags":[],"class_list":["post-3031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/mascaras-carnavalvalida.jpg?fit=752%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3031"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3031\/revisions"}],"predecessor-version":[{"id":3064,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3031\/revisions\/3064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3032"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}