{"id":3048,"date":"2021-02-21T01:50:35","date_gmt":"2021-02-21T01:50:35","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3048"},"modified":"2021-02-27T21:33:55","modified_gmt":"2021-02-27T21:33:55","slug":"ameghino-covid-19-otra-familia-despide-con-dolor-a-un-ser-querido","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/municipios\/florentino-ameghino\/ameghino-covid-19-otra-familia-despide-con-dolor-a-un-ser-querido\/","title":{"rendered":"Ameghino. Covid-19         OTRA FAMILIA DESPIDE CON DOLOR A UN SER QUERIDO."},"content":{"rendered":"\n<p>\u00abLabrujulaweb\u00bb-20\/02\/21. \u00ab<strong>Se trata de un hombre mayor de edad que contrajo Covid hace menos de un mes y permanec\u00eda internado<\/strong>\u00ab.<\/p>\n\n\n\n<p><strong>Lizardo Garcia tenia 87 a\u00f1os, contrajo Covid-19 Positivo hace aproximadamente un mes habiendo sido internado en el Hospital de Ameghino primeramente y luego trasladado a la U.T.I de Gral Pinto, donde falleci\u00f3 este S\u00e1bado.<\/strong><\/p>\n\n\n\n<p>La causa de su deceso se debi\u00f3 a  complicaciones que dej\u00f3  en sus pulmones \u00ab<strong>despu\u00e9s de haber transitado ya la enfermedad y habiendo cumplido con el aislamiento<\/strong>\u00ab.<\/p>\n\n\n\n<p>-Lizardo es un reconocido ciudadano de Ameghino por tratarse del padre de dos ex funcionarios &#8211;<strong>Patricio A. Garcia y Andrea Garcia<\/strong> quienes  han ocupado cargos p\u00fablicos destacados- y quien se mantuvo presente -Junto a su esposa Blanca Medialdea- acompa\u00f1ando en cada etapa pol\u00edtica y en la vida cotidiana a sus hijos-.<\/p>\n\n\n\n<p>Hoy familiares, amigos y vecinos sienten profundamente su partida y despiden sus restos bajo un estricto protocolo vigente Covid-19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es la cuarta victima que se cobra el virus en Ameghino<\/p>\n","protected":false},"author":2,"featured_media":3052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,24],"tags":[],"class_list":["post-3048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-florentino-ameghino"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/02\/Lizardootra.jpg?fit=400%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3048"}],"version-history":[{"count":7,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3048\/revisions"}],"predecessor-version":[{"id":3059,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3048\/revisions\/3059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3052"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}