{"id":3155,"date":"2021-03-17T14:10:04","date_gmt":"2021-03-17T14:10:04","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3155"},"modified":"2021-03-18T14:34:24","modified_gmt":"2021-03-18T14:34:24","slug":"tejedor-covid-19-sin-prisa-pero-sin-pausa-siguen-subiendo-los-activos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/tejedor-covid-19-sin-prisa-pero-sin-pausa-siguen-subiendo-los-activos\/","title":{"rendered":"Tejedor: Covid-19.                 Sin prisa pero sin pausa siguen subiendo los activos."},"content":{"rendered":"\n<p>Desde hace  unas semanas el distrito viene sumando a diario nuevos casos positivos , de los cuales la gran mayor\u00eda corresponden a ciudadanos de la ciudad cabecera y el resto a la localidad de Colonia Ser\u00e9, as\u00ed en el dia de la fecha se detectaron <strong>6 nuevos activos siendo en la actualidad<\/strong> <strong> 26 las personas afectadas<\/strong>,  esto se\u00f1alan los informes que a diario emite la Secretar\u00eda de Prensa Municipal.<\/p>\n\n\n\n<p>-6 nuevos casos positivos activos<br>-5 casos recuperados<\/p>\n\n\n\n<p>Al d\u00eda 17 de marzo, en el distrito de Carlos Tejedor, se registran 154 personas cumpliendo aislamiento domiciliario preventivo, sin presentar signos ni s\u00edntomas compatibles con infecci\u00f3n de Covid-19.<\/p>\n\n\n\n<p>\u2022 26 CASOS POSITIVOS ACTIVOS<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>14 positivos por hisopado, 12 por criterio cl\u00ednico epidemiol\u00f3gico<\/li><li>21 de Carlos Tejedor, 5 de Colonia Ser\u00e9<br>*Total Casos Positivos: 222<\/li><\/ul>\n\n\n\n<p>\u2022 194 CASOS RECUPERADOS \u2022 2 FALLECIDOS \u2022 4 CASOS SOSPECHOSOS<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>2 de Carlos Tejedor; 2 de Tres Algarrobos<\/li><li>\u2022 226 SOSPECHOSOS DESCARTADOS.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42-1024x1024.jpeg?resize=640%2C640\" alt=\"Al dia de hoy suman 6 nuevos activos.\" class=\"wp-image-3156\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-10.22.42.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al dia de hoy se suman 6 nuevos activos.<\/p>\n","protected":false},"author":2,"featured_media":3157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,28,31,6,9],"tags":[],"class_list":["post-3155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carlos-tejedor","category-salud-covid19","category-importantes","category-interes-general","category-municipios"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/03\/COVID-VALIDA.jpg?fit=751%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3155"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3155\/revisions"}],"predecessor-version":[{"id":3158,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3155\/revisions\/3158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3157"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}