{"id":3627,"date":"2021-05-14T17:51:06","date_gmt":"2021-05-14T17:51:06","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3627"},"modified":"2021-05-14T18:04:14","modified_gmt":"2021-05-14T18:04:14","slug":"ameghino-se-confirmo-un-nuevo-fallecido-por-covid","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-se-confirmo-un-nuevo-fallecido-por-covid\/","title":{"rendered":"Ameghino:                                 Se Confirm\u00f3 un nuevo fallecido por Covid."},"content":{"rendered":"\n<p>Se trata de un hombre de 75 a\u00f1os de edad quien hab\u00eda sido derivado a un centro de salud de mayor complejidad hace una semana y falleci\u00f3 este mediod\u00eda.<\/p>\n\n\n\n<p>Al dia de hoy el distrito sigue sumando positivos, con un total de 126 activos y 7 fallecidos.<\/p>\n\n\n\n<p> Si bien hasta ultima hora del dia no se da el parte oficial, trascendi\u00f3 este mediod\u00eda que en Blaquier suma una importante cifra en el dia de hoy y tambi\u00e9n confirmar\u00edan mas activos de Ameghino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al momento son 7 los fallecidos en el Distrito<\/p>\n","protected":false},"author":2,"featured_media":3631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,2,24,6,9],"tags":[],"class_list":["post-3627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-destacadas","category-florentino-ameghino","category-interes-general","category-municipios"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/ULTIMO-MOMENTO-real.png?fit=893%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3627"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3627\/revisions"}],"predecessor-version":[{"id":3632,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3627\/revisions\/3632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3631"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}