{"id":3722,"date":"2021-05-22T23:21:34","date_gmt":"2021-05-22T23:21:34","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3722"},"modified":"2021-05-27T22:58:49","modified_gmt":"2021-05-27T22:58:49","slug":"policiales-ofrecen-un-millon-de-pesos-de-recompensa-por-un-hombre-que-intento-asesinar-a-su-pareja","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/policiales-ofrecen-un-millon-de-pesos-de-recompensa-por-un-hombre-que-intento-asesinar-a-su-pareja\/","title":{"rendered":"Policiales.                      Ofrecen un mill\u00f3n de pesos de recompensa por un hombre que intent\u00f3 asesinar a su pareja"},"content":{"rendered":"\n<p><strong>El \u00abFemicidio en grado de tentativa\u00bb ocurri\u00f3 en Rufino durante febrero de este a\u00f1o. La mujer logr\u00f3 salvar su vida al haber fingido estar muerta.<\/strong><\/p>\n\n\n\n<p>&nbsp;El Gobierno ofreci\u00f3 un mill\u00f3n de pesos de recompensa para poder hallar al hombre que intent\u00f3 matar a pu\u00f1aladas a su pareja en Santa Fe, hecho que no deriv\u00f3 en el femicidio de la v\u00edctima gracias a que se hizo pasar por muerta tras el ataque.<\/p>\n\n\n\n<p>El violento episodio ocurri\u00f3 en Rufino el pasado 14 de febrero por la ma\u00f1ana, cuando Facundo Crocco, de 41 a\u00f1os, acert\u00f3 27 pu\u00f1aladas contra su pareja, Carina Blangetti, un a\u00f1o menor que \u00e9l.<\/p>\n\n\n\n<p>La mujer sobrevivi\u00f3 al cruento ataque gracias a que en ese momento atin\u00f3 a hacerse pasar por muerta, afirm\u00f3 su padre, Jos\u00e9 Blangetti.<\/p>\n\n\n\n<p>\u00ab\u00c9l sal\u00eda, entraba, le pegaba una pu\u00f1alada y volv\u00eda salir\u00bb, relat\u00f3 el padre de la v\u00edctima, quien afirm\u00f3 que Carina salv\u00f3 su vida porque \u00abse hizo pasar por muerta\u00bb. El hombre se\u00f1al\u00f3 que \u00abla \u00faltima vez que ingres\u00f3 a la casa le dijo: `te pego la \u00faltima pu\u00f1alada porque ya est\u00e1s muerta\u00b4 y que se ir\u00eda al campo y se matar\u00eda\u00bb.<\/p>\n\n\n\n<p>\u00abAlgo ha tomado este chico, no s\u00e9 qu\u00e9, no entiendo nada, si tom\u00f3 alcohol o drogas y se le ha dado vuelta la cabeza\u00bb, manifest\u00f3 Blangetti, quien defini\u00f3 a Crocco como \u00abun muchacho muy servicial, muy atento con la gente\u00bb.<\/p>\n\n\n\n<p>Tras intentar asesinar a la mujer, Facundo Crocco se escap\u00f3 y actualmente se encuentra pr\u00f3fugo de la Justicia, que lo busca en la causa que lo tiene imputado por \u00abTentativa de femicidio\u00bb.<\/p>\n\n\n\n<p>Por esa raz\u00f3n, el fiscal Horacio Pueyrred\u00f3n solicit\u00f3 al Gobierno nacional que ofrezca una recompensa para poder hallar al violento hombre.<\/p>\n\n\n\n<p>La suma de dinero asciende a un mill\u00f3n de pesos, seg\u00fan lo establecido por la Resoluci\u00f3n 225\/2021 del Ministerio de Seguridad, publicada este viernes en el Bolet\u00edn Oficial.<\/p>\n\n\n\n<p>La recompensa est\u00e1 destinada a \u00abaquellas personas que, brinden datos \u00fatiles que permitan lograr la captura de Facundo Esteban Crocco, argentino, titular del D.N.I. N\u00b0 27.419.922, nacido el 06 de agosto de 1979, hijo de Elvio Osvaldo y de Lidia Isabel Posee, con \u00faltimo domicilio conocido en la calle Carballeira 662 y 702, ciudad de Rufino, provincia de Santa Fe, sobre quien pesa pedido de captura desde el 14 de febrero de 2021\u00bb.<\/p>\n\n\n\n<p>\u00abAl mencionado pr\u00f3fugo se le atribuye el hecho ocurrido el 14 de febrero de 2021, aproximadamente a las 07:30 horas, momento en el cual habr\u00eda agredido f\u00edsicamente con un arma blanca a una mujer, caus\u00e1ndole lesiones graves con la intenci\u00f3n de causarle la muerte\u00bb, agreg\u00f3 el texto publicado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente: La Marca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00abFemicidio en grado de tentativa\u00bb ocurri\u00f3 en Rufino durante febrero de este a\u00f1o. La mujer logr\u00f3 salvar su vida al haber fingido estar muerta. &nbsp;El Gobierno ofreci\u00f3 un mill\u00f3n de pesos de recompensa para poder hallar al hombre que intent\u00f3 matar a pu\u00f1aladas a su pareja en Santa Fe, hecho que no deriv\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,6,34],"tags":[],"class_list":["post-3722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-interes-general","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/PROFUGOvalido.png?fit=872%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3722"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3722\/revisions"}],"predecessor-version":[{"id":3725,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3722\/revisions\/3725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3723"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}