{"id":3754,"date":"2021-05-24T00:03:56","date_gmt":"2021-05-24T00:03:56","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3754"},"modified":"2021-05-26T21:59:55","modified_gmt":"2021-05-26T21:59:55","slug":"sampacho-llora-al-despedir-los-restos-mortales-del-intendente-municipal-flavio-alejandro-juarez","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/sampacho-llora-al-despedir-los-restos-mortales-del-intendente-municipal-flavio-alejandro-juarez\/","title":{"rendered":"SAMPACHO LLORA  AL DESPEDIR LOS RESTOS MORTALES DEL INTENDENTE MUNICIPAL FLAVIO ALEJANDRO JU\u00c1REZ"},"content":{"rendered":"\n<p><strong>Marcada la historia de un joven Intendente municipal de Sampacho (Cordoba) que dej\u00f3 su vida en la lucha de esta Covid-19 letal. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"629\" height=\"500\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/INTEMDENTE-VALIDA.jpg?resize=629%2C500\" alt=\"\" data-id=\"3756\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=3756\" class=\"wp-image-3756\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/INTEMDENTE-VALIDA.jpg?w=629&amp;ssl=1 629w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/INTEMDENTE-VALIDA.jpg?resize=300%2C238&amp;ssl=1 300w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-VALIDA1.jpg?resize=640%2C480\" alt=\"\" data-id=\"3757\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-VALIDA1.jpg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=3757\" class=\"wp-image-3757\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-VALIDA1.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-VALIDA1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-VALIDA1.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Flavio Alejandro Ju\u00e1rez tenia Solo 49 a\u00f1os de edad <\/strong>y un a\u00f1o y meses de gobierno no fueron la excepci\u00f3n para dejar su impronta.<\/p>\n\n\n\n<p>Su urna funeraria recorri\u00f3 las calles del pueblo que lo despidi\u00f3 con gran congoja, trasladado por la autobomba y escoltado por Bomberos Voluntarios locales. A su paso se depositaban flores, banderas y fervientes aplausos.<\/p>\n\n\n\n<p>Sus padres (hijo \u00fanico), familiares, amigos y todos los integrantes de la sociedad estuvieron presentes en el cementerio para depositar los restos mortales. Ju\u00e1rez padeci\u00f3 de la Covid-19, internado por m\u00e1s de 21 d\u00edas, hicieron todo lo humanamente posible hasta que su cuerpo dejo de luchar. A\u00fan su pueblo no puede creer lo acontecido, Flavio Alejandro Ju\u00e1rez el primer Intendente que fallece en ejercicio de sus funciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Localidad de Rio Cuarto ubicada al Sur de Cordoba<\/p>\n","protected":false},"author":2,"featured_media":3755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,31,6],"tags":[],"class_list":["post-3754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19","category-importantes","category-interes-general"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/05\/SAMPACHO-2VALIDA.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3754"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3754\/revisions"}],"predecessor-version":[{"id":3758,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3754\/revisions\/3758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3755"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}