{"id":3897,"date":"2021-06-08T20:24:41","date_gmt":"2021-06-08T23:24:41","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3897"},"modified":"2021-06-11T18:11:23","modified_gmt":"2021-06-11T21:11:23","slug":"importante-reunion-en-el-ministerio-de-transporte-por-la-continuidad-de-la-terminal-de-villegas","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/importante-reunion-en-el-ministerio-de-transporte-por-la-continuidad-de-la-terminal-de-villegas\/","title":{"rendered":"IMPORTANTE REUNION EN EL MINISTERIO DE TRANSPORTE POR LA CONTINUIDAD DE LA TERMINAL DE VILLEGAS."},"content":{"rendered":"\n<p>(labrujulaweb 08-06-21) <strong> <em>En la tarde de este Martes se mantuvo un encuentro entre el concejal del F.R Horacio Pascual y el Ministro de Transporte de la Naci\u00f3n Alexis Guerrera.<\/em><\/strong><\/p>\n\n\n\n<p>En el despacho del piso 12 del Ministerio de Transporte de la Naci\u00f3n el edil Vill\u00e9guense mantuvo un encuentro con el Ministro Guerrera cuyo tema principal fue la inquietud  por interiorizar al funcionario Nacional sobre la continuidad de la terminal de \u00f3mnibus de la ciudad que comenz\u00f3 a construirse llegando a una etapa avanzada, quedando inconclusa desde que finalizara la gesti\u00f3n de Gilberto Alegre en el a\u00f1o 2015.<\/p>\n\n\n\n<p>\u201cLogramos interiorizar al Ministro \u2013explic\u00f3 Pascual-sobre el avance que tuvo la obra en sus comienzos con fondos provinciales y que no supimos m\u00e1s porqu\u00e9 se detuvo,<strong> queremos saber en qu\u00e9 condiciones se retir\u00f3 la empresa, si qued\u00f3 alguna deuda, en qu\u00e9 instancia est\u00e1n los tramites de la obra que hoy sufre un gran deterioro,<\/strong> destacando que es un tr\u00e1mite que f\u00e1cilmente puede hacer el Intendente Campana resolviendo todo lo pendiente que hubiere entre Provincia y Municipio.<\/p>\n\n\n\n<p><strong>\u201cEstamos dispuestos a acompa\u00f1ar y a trabajar juntos para que la obra finalice. pero para eso el Intendente debe gestionar y volver a firmar convenios\u00bb<\/strong>.&nbsp; Con toda esa informaci\u00f3n el Ministro Guerrera comprometi\u00f3 la intervenci\u00f3n del Ministerio a su cargo para que finalmente se logre el objetivo \u2013concluy\u00f3 Pascual- <strong>\u201cTerminar la terminal de \u00d3mnibus en un lugar estrat\u00e9gico del ingreso a la ciudad sin la necesidad de entrar a la misma con los inconvenientes que eso implica\u00bb<\/strong>, adem\u00e1s salvar un edificio que se deteriora al paso del tiempo \u2013 finaliz\u00f3-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(labrujulaweb 08-06-21) En la tarde de este Martes se mantuvo un encuentro entre el concejal del F.R Horacio Pascual y el Ministro de Transporte de la Naci\u00f3n Alexis Guerrera. En el despacho del piso 12 del Ministerio de Transporte de la Naci\u00f3n el edil Vill\u00e9guense mantuvo un encuentro con el Ministro Guerrera cuyo tema principal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25,10,31,6,9,29],"tags":[],"class_list":["post-3897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-villegas","category-gobierno","category-importantes","category-interes-general","category-municipios","category-politica-estado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/ALEXIS-PASCUALVALIDA.jpg?fit=750%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3897"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3897\/revisions"}],"predecessor-version":[{"id":3934,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3897\/revisions\/3934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3898"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}