{"id":3928,"date":"2021-06-11T18:10:17","date_gmt":"2021-06-11T21:10:17","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=3928"},"modified":"2021-06-12T23:35:08","modified_gmt":"2021-06-13T02:35:08","slug":"tejedor-se-anuncio-una-sala-de-faena-desposte-y-camara-frigorifica-para-especie-porcina","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/industria-comercio\/tejedor-se-anuncio-una-sala-de-faena-desposte-y-camara-frigorifica-para-especie-porcina\/","title":{"rendered":"Tejedor.                                     SE ANUNCI\u00d3 UNA SALA DE FAENA, DESPOSTE Y C\u00c1MARA FRIGORIFICA PARA  ESPECIE PORCINA."},"content":{"rendered":"\n<p>La noticia di\u00f3 un cierre de semana aliviador para el sector de peque\u00f1os y medianos productores. <strong>\u00abEl Distrito de Tejedor contara con una sala de faena, desposte y c\u00e1mara frigor\u00edfica para la especie porcina\u00bb<\/strong>.<\/p>\n\n\n\n<p>El anuncio lo dio a conocer este Viernes la Intendenta Municipal Maria C Gianini Junto al Ministro de Desarrollo Agrario Dr. Javier Rodr\u00edguez -de manera remota- y <strong>en el marco del Programa Provincial de Fortalecimiento de las cadenas productivas del Plan de Reactivaci\u00f3n \u201cProvincia en Marcha\u201d,<\/strong> anunciado por el gobernador Axel Kicillof.<\/p>\n\n\n\n<p>Esto surge a trav\u00e9s de un convenio firmado entre el Ministerio de Desarrollo Agrario y el Municipio, quienes dieron detalles de las instalaciones.<\/p>\n\n\n\n<p> <strong>La planta principal  tendr\u00e1 la capacidad de faenar 30 cerdos por d\u00eda contar\u00e1 con una superficie de 180 metros cuadrados, con zona sucia, intermedia y limpia, sala de desposte y troceado, c\u00e1mara frigor\u00edfica, dock de carga, ba\u00f1os, vestuarios y oficina veterinaria, adem\u00e1s dos piletones para el manejo de efluentes y una sala de faena de emergencia de 70 metros cuadrados.<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;\u00abEn los pr\u00f3ximos d\u00edas el Municipio realizar\u00e1 la licitaci\u00f3n correspondiente y a la brevedad comenzaremos con la ejecuci\u00f3n y concreci\u00f3n de este proyecto para la producci\u00f3n de productores y comerciantes, fortaleciendo la ruralidad del distrito\u00bb. \u2013 destac\u00f3 la Intendenta Gianini.<\/p>\n\n\n\n<p>Esto nos permitir\u00e1 \u2013explicaron tanto del Drtor de Producci\u00f3n German Del Valle como el Concejal Armando Palau-quienes estuvieron en la mesa de presentaci\u00f3n- <strong>la recuperaci\u00f3n de productores que abandonaron la actividad, promoviendo nuevos emprendedores, apoyados con financiamiento, asistencia t\u00e9cnica y capacitaci\u00f3n<\/strong>&#8211; aseguraron- Podr\u00e1n vender o procesar su propia carne en condiciones de salubridad e higiene adecuadas y habilitadas para su comercializaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/del-vallevalida.jpg?resize=640%2C480\" alt=\"\" data-id=\"3930\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=3930\" class=\"wp-image-3930\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/del-vallevalida.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/del-vallevalida.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/del-vallevalida.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"blocks-gallery-item__caption\">German Del Valle Drtor Producci\u00f3n<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-armando.jpg?resize=640%2C480\" alt=\"\" data-id=\"3931\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-armando.jpg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=3931\" class=\"wp-image-3931\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-armando.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-armando.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-armando.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"blocks-gallery-item__caption\">Armando Palau Cjal F.D.T<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>En tanto el Ministro de Desarrollo Agrario de la Provincia destac\u00f3 el trabajo articulado que viene realizando todo el equipo de gesti\u00f3n.<strong> \u201cHoy poder estar concretando este frigor\u00edfico porcino en Tejedor nos da la certeza que seguiremos trabajando para fomentar la industrializaci\u00f3n de la producci\u00f3n agropecuaria y que se haga de manera regional es un tema que venimos hablando mucho con el Gobernador<\/strong> <strong>quien tiene una posici\u00f3n muy clara de seguir apostando al crecimiento de los distritos con estas acciones\u00bb<\/strong>-remarc\u00f3-<\/p>\n\n\n\n<p>Cuando tomo la palabra nuevamente la primera mandataria Tejedorense Finaliz\u00f3 remarcando que<strong> \u00abesto es una parte de lo que seguir\u00e1 en crecimiento,  con el objetivo de que esta sala se ampli\u00e9 dando lugar a peque\u00f1os y medianos productores de contar con un espacio adecuado y generar mano de obra calificada.<\/strong>\u00ab<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-tejedor-interior.jpg?resize=426%2C318\" alt=\"\" class=\"wp-image-3932\" width=\"426\" height=\"318\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-tejedor-interior.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-tejedor-interior.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/valida-tejedor-interior.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/><figcaption>Ministro De Desarrollo Pcial Javier Rodriguez por Zoom<\/figcaption><\/figure><\/div>\n\n\n\n<p>El anuncio se realiz\u00f3 en la sala del Honorable Consejo Deliberante y acompa\u00f1aron -ademas de funcionarios de la gesti\u00f3n- Representantes de entidades rurales, comerciante, c\u00e1mara de comercio, Senasa, Pte. del Consejo Deliberante y Concejales de todos los bloques del Distrito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cierre de semana con una noticia que trae alivio economico a peque\u00f1os y medianos productores<\/p>\n","protected":false},"author":2,"featured_media":3929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32,26,31,5,6,29],"tags":[],"class_list":["post-3928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro-negocios","category-carlos-tejedor","category-importantes","category-industria-comercio","category-interes-general","category-politica-estado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/TEJEDOR-HOYvalida.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3928"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3928\/revisions"}],"predecessor-version":[{"id":3955,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3928\/revisions\/3955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/3929"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}