{"id":4106,"date":"2021-06-27T19:59:30","date_gmt":"2021-06-27T22:59:30","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=4106"},"modified":"2021-06-29T19:48:03","modified_gmt":"2021-06-29T22:48:03","slug":"el-desafio-de-inmunizar-a-los-mas-chicos","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/el-desafio-de-inmunizar-a-los-mas-chicos\/","title":{"rendered":"El desaf\u00edo de inmunizar a los m\u00e1s chicos"},"content":{"rendered":"\n<p>El gobierno proyecta un escenario de mayor alivio para septiembre y la inoculaci\u00f3n de los menores podr\u00eda iniciarse en el mediano plazo. Mientras tanto, las variantes obligan a mantener los cuidados.&nbsp;<\/p>\n\n\n\n<p>Con una buena cantidad de dosis aseguradas, las autoridades sanitarias argentinas comienzan a evaluar la&nbsp;<strong>protecci\u00f3n&nbsp;a los menores de 18 a\u00f1os<\/strong>. La compra de 24 millones de dosis de la vacuna china&nbsp;<strong>Sinopharm<\/strong>&nbsp;se confirma apenas dos semanas despu\u00e9s que ese pa\u00eds autorizara la inoculaci\u00f3n para ni\u00f1os de 3 a 17 a\u00f1os. Con el objetivo avanzado de lograr la inmunidad en j\u00f3venes y adultos, en el mundo se plantea ya el desaf\u00edo de proteger a los m\u00e1s chicos. Desde el gobierno nacional avanzan tambi\u00e9n en las negociaciones para obtener dosis de&nbsp;<strong>Pfizer<\/strong>&nbsp;con ese objetivo, pues, la tecnolog\u00eda elaborada por la farmac\u00e9utica de Estados Unidos es una de las f\u00f3rmulas autorizadas para su inoculaci\u00f3n a partir de los 12 a\u00f1os.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de los avances de los diferentes laboratorios, para que una sustancia activa pueda ser utilizada en menores,&nbsp;<strong>previamente, debe ser autorizada por Anmat.<\/strong>&nbsp;En el pa\u00eds, seg\u00fan se estima, viven entre 13 y 15 millones de personas menores de 18 a\u00f1os,<\/p>\n\n\n\n<p>La inmunizaci\u00f3n de los m\u00e1s peque\u00f1os y adolescentes es fundamental si el objetivo de Argentina es alcanzar la inmunidad de reba\u00f1o, es decir, inocular entre el 60 por ciento y 70 por ciento de la sociedad.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el envi\u00f3n de la vacunaci\u00f3n de adultos, el objetivo ahora es cubrir a toda la poblaci\u00f3n<\/p>\n","protected":false},"author":2,"featured_media":4107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,31,6,29],"tags":[],"class_list":["post-4106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-importantes","category-interes-general","category-politica-estado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/06\/NI%C3%91OSVALIS.jpeg?fit=750%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4106"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4106\/revisions"}],"predecessor-version":[{"id":4145,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4106\/revisions\/4145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/4107"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}