{"id":4801,"date":"2021-09-13T12:47:17","date_gmt":"2021-09-13T15:47:17","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=4801"},"modified":"2021-09-14T19:33:21","modified_gmt":"2021-09-14T22:33:21","slug":"ameghino-denuncian-un-robo-y-la-policia-lo-encuentra-cuando-se-lo-llevaba-el-camion-recolector-de-basura","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-denuncian-un-robo-y-la-policia-lo-encuentra-cuando-se-lo-llevaba-el-camion-recolector-de-basura\/","title":{"rendered":"Ameghino:                       Denuncian Un Robo y La Polic\u00eda lo encuentra cuando se lo llevaba el Cami\u00f3n Recolector de Basura."},"content":{"rendered":"\n<p>En horas de la madrugada de este lunes el llamado al 101 de un vecino, mayor de edad, alerta a la polic\u00eda sobre el robo en su domicilio de barrio F\u00e1tima.<\/p>\n\n\n\n<p>Cuando arriba el personal policial constat\u00f3 la veracidad de los hechos y el due\u00f1o de la vivienda manifiesta que le sustrajeron el televisor, es as\u00ed que proceden a realizar la investigaci\u00f3n encontrando inmediatamente a escasos metros de la vivienda a un cami\u00f3n recolector que levantaba el objeto de la vereda  entendiendo que lo hab\u00edan tirado a la basura.<\/p>\n\n\n\n<p>La polic\u00eda recupera el elemento sustra\u00eddo y da con el autor del il\u00edcito -un hombre mayor de edad-  en tanto se traslada a la v\u00edctima a radicar la denuncia, quien finalmente expresa no querer denunciar, retir\u00e1ndose de la dependencia policial, por lo que la polic\u00eda inicia actuaciones de oficio.<\/p>\n\n\n\n<p>El hecho qued\u00f3 esclarecido con intervenci\u00f3n de Ayudant\u00eda Fiscal Ameghino y  caratulado \u201cTENTATIVA DE HURTO\u201d ya que el individuo que cometi\u00f3 el il\u00edcito &#8211; por razones que no se pudieron establecer- abandona el elemento sustra\u00eddo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la madrugada de este lunes el llamado al 101 de un vecino, mayor de edad, alerta a la polic\u00eda sobre el robo en su domicilio de barrio F\u00e1tima. Cuando arriba el personal policial constat\u00f3 la veracidad de los hechos y el due\u00f1o de la vivienda manifiesta que le sustrajeron el televisor, es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,34],"tags":[],"class_list":["post-4801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/AMEGHINOpolicial-valida.jpg?fit=882%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4801"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4801\/revisions"}],"predecessor-version":[{"id":4803,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4801\/revisions\/4803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/4802"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}