{"id":4833,"date":"2021-09-18T04:43:43","date_gmt":"2021-09-18T07:43:43","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=4833"},"modified":"2021-09-20T10:42:25","modified_gmt":"2021-09-20T13:42:25","slug":"ameghino-considerable-vuelco-el-conductor-quedo-atrapado-en-el-vehiculo","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-considerable-vuelco-el-conductor-quedo-atrapado-en-el-vehiculo\/","title":{"rendered":"Ameghino:      CONSIDERABLE VUELCO, EL CONDUCTOR QUED\u00d3 ATRAPADO EN EL VEHICULO."},"content":{"rendered":"\n<p>El accidente se produjo en horas de la madrugada, el vuelco de un veh\u00edculo marca Fiat Strada en cercan\u00edas del Parque Municipal y Basurero.<\/p>\n\n\n\n<p>Por causas que a\u00fan no se establecieron un veh\u00edculo marca Fiat Strada que transitaba en direcci\u00f3n Blaquier Ameghino, perdi\u00f3 el control, produci\u00e9ndose un vuelco considerable.<\/p>\n\n\n\n<p>A ra\u00edz del estado en que qued\u00f3 el veh\u00edculo, su conductor &#8211; <strong>una persona joven de sexo masculino oriundo de Ameghino- <\/strong>qued\u00f3 atrapado dentro del habit\u00e1culo hasta que la ardua tarea de bomberos, polic\u00eda y personal de SAME pudieron rescatarlo.<\/p>\n\n\n\n<p>Inmediatamente fue trasladado por personal del SAME al Hospital Felipe Pel\u00e1ez con heridas y en estado consiente.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Accidente en Ameghino\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/EQtPe8EUCic?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDEENTE-VALIDO.jpg?resize=640%2C480\" alt=\"\" data-id=\"4836\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-considerable-vuelco-el-conductor-quedo-atrapado-en-el-vehiculo\/attachment\/accideente-valido\/\" class=\"wp-image-4836\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDEENTE-VALIDO.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDEENTE-VALIDO.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDEENTE-VALIDO.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDENTE-VALIDO4.jpg?resize=640%2C480\" alt=\"\" data-id=\"4837\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-considerable-vuelco-el-conductor-quedo-atrapado-en-el-vehiculo\/attachment\/accidente-valido4\/\" class=\"wp-image-4837\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDENTE-VALIDO4.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDENTE-VALIDO4.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDENTE-VALIDO4.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/FIAR-VALIDA-2.jpeg?resize=640%2C360\" alt=\"\" data-id=\"4839\" data-full-url=\"http:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/FIAR-VALIDA-2.jpeg\" data-link=\"http:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-considerable-vuelco-el-conductor-quedo-atrapado-en-el-vehiculo\/attachment\/fiar-valida-2\/\" class=\"wp-image-4839\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/FIAR-VALIDA-2.jpeg?w=889&amp;ssl=1 889w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/FIAR-VALIDA-2.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/FIAR-VALIDA-2.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El accidente se produjo en horas de la madrugada, el vuelco de un veh\u00edculo marca Fiat Strada en cercan\u00edas del Parque Municipal y Basurero. Por causas que a\u00fan no se establecieron un veh\u00edculo marca Fiat Strada que transitaba en direcci\u00f3n Blaquier Ameghino, perdi\u00f3 el control, produci\u00e9ndose un vuelco considerable. A ra\u00edz del estado en que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,34],"tags":[],"class_list":["post-4833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/ACCIDENTE-VALIDO3.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4833"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4833\/revisions"}],"predecessor-version":[{"id":4840,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4833\/revisions\/4840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/4834"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}