{"id":4847,"date":"2021-09-19T01:33:53","date_gmt":"2021-09-19T04:33:53","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=4847"},"modified":"2021-09-19T01:53:42","modified_gmt":"2021-09-19T04:53:42","slug":"dos-sujetos-de-ameghino-viajaban-con-marihuana-y-fueron-detenidos-en-lincoln","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/dos-sujetos-de-ameghino-viajaban-con-marihuana-y-fueron-detenidos-en-lincoln\/","title":{"rendered":"Dos Sujetos de Ameghino Viajaban con Marihuana y fueron detenidos en Lincoln"},"content":{"rendered":"\n<p>Personal del Destacamento Seguridad Vial de Lincoln realiz\u00f3 operativo de interceptaci\u00f3n vehicular en ruta 188 km 219 y procedi\u00f3 a interceptar a veh\u00edculo Chevrolet Aveo ocupado por <strong>dos ciudadanos masculinos Mayores de edad oriundos de la ciudad de Florentino Ameghino <\/strong>a quienes se le incaut\u00f3 en su poder trozo compacto de picadura de Marihuana (cannabis) arrojando un peso de 465.2 grs.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/MARIHUANA-VALIDA.jpeg?resize=375%2C437\" alt=\"\" class=\"wp-image-4849\" width=\"375\" height=\"437\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/MARIHUANA-VALIDA.jpeg?w=429&amp;ssl=1 429w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/MARIHUANA-VALIDA.jpeg?resize=257%2C300&amp;ssl=1 257w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure><\/div>\n\n\n\n<p> Intervino UFI especializado en estupefacientes de Jun\u00edn Dr. Lopardo.<br>Comisario Gabriel Nelson Rojas. Jefe Destacamento Seguridad VIAL Lincoln.<\/p>\n\n\n\n<p>Fuente: Democracia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal del Destacamento Seguridad Vial de Lincoln realiz\u00f3 operativo de interceptaci\u00f3n vehicular en ruta 188 km 219 y procedi\u00f3 a interceptar a veh\u00edculo Chevrolet Aveo ocupado por dos ciudadanos masculinos Mayores de edad oriundos de la ciudad de Florentino Ameghino a quienes se le incaut\u00f3 en su poder trozo compacto de picadura de Marihuana (cannabis) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2,24,6,9,34],"tags":[],"class_list":["post-4847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-florentino-ameghino","category-interes-general","category-municipios","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/09\/MARIHUANA-AVALIDA.jpeg?fit=394%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4847"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4847\/revisions"}],"predecessor-version":[{"id":4851,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4847\/revisions\/4851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/4848"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}