{"id":5244,"date":"2021-11-09T19:06:57","date_gmt":"2021-11-09T22:06:57","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=5244"},"modified":"2021-11-12T19:02:04","modified_gmt":"2021-11-12T22:02:04","slug":"acusan-a-un-financista-oriundo-de-lincoln-de-integrar-una-banda-criminal-en-rosario","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/acusan-a-un-financista-oriundo-de-lincoln-de-integrar-una-banda-criminal-en-rosario\/","title":{"rendered":"Acusan a un financista oriundo de Lincoln de integrar una banda criminal en Rosario"},"content":{"rendered":"\n<p>Un&nbsp;<strong>financista<\/strong>&nbsp;oriundo de<strong>&nbsp;Lincoln<\/strong>, que vive en la provincia de&nbsp;<strong>Santa Fe<\/strong>&nbsp;desde hace m\u00e1s de una d\u00e9cada, se encuentra<strong>&nbsp;acusado<\/strong>&nbsp;en una causa penal por integrar una&nbsp;<strong>banda criminal&nbsp;<\/strong>que fue desbaratada el mes pasado por la&nbsp;<strong>Polic\u00eda Federal<\/strong>. El imputado a\u00fan no se present\u00f3 ante la&nbsp;<strong>Justicia<\/strong>&nbsp;y tiene orden de captura, porque ser\u00eda el<strong>&nbsp;nexo<\/strong>&nbsp;entre la&nbsp;<strong>banda narco<\/strong>&nbsp;y las<strong>&nbsp;\u00abcuevas\u00bb financieras<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/PUBLI.gif?resize=300%2C200&#038;ssl=1\" alt=\"\" class=\"wp-image-5257\"\/><\/figure>\n\n\n\n<p>Seg\u00fan surge del&nbsp;<strong>expediente judicial<\/strong>, el linque\u00f1o se dedicaba al&nbsp;<strong>intercambio de divisas<\/strong>&nbsp;(de peso a d\u00f3lar) en cuevas financieras en pleno centro de la ciudad de Rosario. La investigaci\u00f3n asegura que un importante<strong>&nbsp;narcotraficante peruano<\/strong>&nbsp;coordinaba las acciones de la organizaci\u00f3n desde el&nbsp;<strong>penal&nbsp;<\/strong>de&nbsp;<strong>Marcos Paz<\/strong>.<\/p>\n\n\n\n<p>Una de las caracter\u00edsticas de esta banda criminal era que sus actividades de&nbsp;<strong>acopio&nbsp;<\/strong>y&nbsp;<strong>distribuci\u00f3n de droga<\/strong>&nbsp;se desarrollaban en departamentos de alquiler temporario ubicados en&nbsp;<strong>pleno centro<\/strong>&nbsp;de Rosario, que rotaban permanentemente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/FPOTO3VALIDA.jpg?resize=422%2C316&#038;ssl=1\" alt=\"\" class=\"wp-image-5246\" width=\"422\" height=\"316\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/FPOTO3VALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/FPOTO3VALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/FPOTO3VALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 422px) 100vw, 422px\" \/><figcaption>Dinero secuetrado en el allanamiento<\/figcaption><\/figure>\n\n\n\n<p>El 14 y 15 de octubre de este a\u00f1o, el&nbsp;<strong>Juzgado Federal de Rosario<\/strong>&nbsp;orden\u00f3 m\u00faltiples allanamientos en diferentes locaciones donde se encontraron alrededor de&nbsp;<strong>34 millones de pesos<\/strong>&nbsp;y&nbsp;<strong>30.572 d\u00f3lares<\/strong>. Tambi\u00e9n incautaron armas y cerca de<strong>&nbsp;2.500 municiones<\/strong>&nbsp;de distinto calibre.<\/p>\n\n\n\n<p>Se logr\u00f3 detener a varios&nbsp;<strong>individuos<\/strong>&nbsp;de la banda, aunque algunos lograron&nbsp;<strong>fugarse<\/strong>, entre ellos,&nbsp;<strong>el linque\u00f1o<\/strong>, que contin\u00faa&nbsp;<strong>sin presentarse ante la justicia<\/strong>.<\/p>\n\n\n\n<p>FUENTE::DEMOCRACIA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&nbsp;financista&nbsp;oriundo de&nbsp;Lincoln, que vive en la provincia de&nbsp;Santa Fe&nbsp;desde hace m\u00e1s de una d\u00e9cada, se encuentra&nbsp;acusado&nbsp;en una causa penal por integrar una&nbsp;banda criminal&nbsp;que fue desbaratada el mes pasado por la&nbsp;Polic\u00eda Federal. El imputado a\u00fan no se present\u00f3 ante la&nbsp;Justicia&nbsp;y tiene orden de captura, porque ser\u00eda el&nbsp;nexo&nbsp;entre la&nbsp;banda narco&nbsp;y las&nbsp;\u00abcuevas\u00bb financieras. Seg\u00fan surge del&nbsp;expediente judicial, el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[31,6,34],"tags":[],"class_list":["post-5244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-importantes","category-interes-general","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2021\/11\/FOTO2VALIDA.jpg?fit=750%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":4,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5244\/revisions"}],"predecessor-version":[{"id":5272,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5244\/revisions\/5272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/5245"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=5244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=5244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}