{"id":601,"date":"2020-08-26T12:14:23","date_gmt":"2020-08-26T12:14:23","guid":{"rendered":"http:\/\/www.labrujulaweb.com.ar\/blog\/?p=601"},"modified":"2020-08-26T12:14:26","modified_gmt":"2020-08-26T12:14:26","slug":"c-tejedor-dos-nuevos-sospechosos-a-la-espera-de-resultados","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/salud-covid19\/c-tejedor-dos-nuevos-sospechosos-a-la-espera-de-resultados\/","title":{"rendered":"C.Tejedor Dos nuevos sospechosos a la espera de resultados"},"content":{"rendered":"\n<p>La Direcci\u00f3n de Salud de Florentino Ameghino informa:<br>En el d\u00eda de hoy, mi\u00e9rcoles 26 de agosto, se registra cuatro (4) casos sospechosos de Coronavirus COVID-19, a la espera de resultados de laboratorio.<\/p>\n\n\n\n<p>28 personas se encuentran cumpliendo la cuarentena preventiva, siendo todos monitoreados en forma diaria por el equipo de salud. Ninguno de ellos ha presentado s\u00edntomas hasta el momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asi lo informo la Secretaria de Prensa del Municipio.<\/p>\n","protected":false},"author":2,"featured_media":602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-covid19"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2020\/08\/COVID-TEJEDOR.jpg?fit=1280%2C1273&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=601"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/601\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/601\/revisions\/603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/602"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}