{"id":6140,"date":"2022-03-28T20:57:57","date_gmt":"2022-03-28T23:57:57","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6140"},"modified":"2022-03-31T12:09:27","modified_gmt":"2022-03-31T15:09:27","slug":"ameghino-jornada-de-educacion-que-dejo-fondos-compromiso-capacitacion-entrega-de-materiales-y-espacios-de-formacion","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-jornada-de-educacion-que-dejo-fondos-compromiso-capacitacion-entrega-de-materiales-y-espacios-de-formacion\/","title":{"rendered":"Ameghino:                        Jornada de educaci\u00f3n que dej\u00f3: Fondos, Compromiso, Capacitaci\u00f3n, entrega de materiales y espacios de formaci\u00f3n."},"content":{"rendered":"\n<p><strong><em>Con la presencia de autoridades del Ministerio de Educaci\u00f3n de la Naci\u00f3n y La Provincia de Bs As Ameghino fue parte de una jornada ampliamente productiva para los niveles t\u00e9cnico-Agrarios<\/em><\/strong><\/p>\n\n\n\n<p>Durante la ma\u00f1ana y parte de la tarde de este Lunes se fueron realizando tareas y anuncios en simultaneo en los niveles secundarios de ense\u00f1anza <strong>t\u00e9cnica y agraria.<\/strong><\/p>\n\n\n\n<p>Primeramente, se hizo entrega de<strong> $12.000.000<\/strong> (doce millones de pesos) en equipamiento para la escuela de educaci\u00f3n <strong>Secundaria t\u00e9cnica N\u00b01. <\/strong>Distribuidas en tornos e implementos para aprendizaje y formaci\u00f3n  de los alumnos. A su vez un nutrido n\u00famero de j\u00f3venes alumnos firmaron un <strong>acuerdo<\/strong> que expresa su compromiso de asistir a la escuela y avanzar en su trayectoria educativa para ser becario\/a de PROGRESAR 16 y 17 a\u00f1os.<\/p>\n\n\n\n<p>Con el objetivo de promover la formaci\u00f3n profesional y capacitaci\u00f3n laboral en el distrito se instal\u00f3 un \u201c<strong>Aula Taller M\u00f3vil<\/strong>\u201d, donde vecinos, alumnos y profesores recibir\u00e1n formaci\u00f3n en soldadura y que perdurar\u00e1 por el termino de 15 d\u00edas.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNNADDAVALIDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6142\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6142\" class=\"wp-image-6142\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNNADDAVALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNNADDAVALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNNADDAVALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAAAAVALIDAA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6144\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6144\" class=\"wp-image-6144\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAAAAVALIDAA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAAAAVALIDAA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAAAAVALIDAA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAVALI.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6145\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAVALI.jpg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6145\" class=\"wp-image-6145\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAVALI.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAVALI.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADAVALI.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Por otra parte, se hizo entrega de un monto de <strong>$500.000<\/strong> (quinientos mil pesos) a la Escuela <strong>Secundaria T\u00e9cnica N\u00b01<\/strong> <strong>$40.000<\/strong> (cuarenta mil pesos) al Centro de Formaci\u00f3n Laboral y <strong>$500.000<\/strong> (quinientos mil pesos) a la Escuela <strong>Secundaria Agraria<\/strong>, destinados a la compra de insumos y materiales.<\/p>\n\n\n\n<p>En tanto en la Escuela Secundaria N\u00b0 3 \u201cRene Favaloro\u201d se instal\u00f3 un <strong>Laboratorio M\u00f3vil<\/strong> adem\u00e1s de hacer entrega de materiales y kits de rob\u00f3tica y puesta en marcha de \u201c<strong>Conectar Igualdad<\/strong>\u201d equipamiento y creaci\u00f3n de espacios de formaci\u00f3n para docentes en el \u00e1rea, programaci\u00f3n y sistema operativo <strong>Huayra.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JONADAVALIDA-1.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6146\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6146\" class=\"wp-image-6146\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JONADAVALIDA-1.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JONADAVALIDA-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JONADAVALIDA-1.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORDAVALIDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6147\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6147\" class=\"wp-image-6147\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORDAVALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORDAVALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORDAVALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNAVALDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6148\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNAVALDA.jpg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6148\" class=\"wp-image-6148\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNAVALDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNAVALDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNAVALDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>As\u00ed fue finalizando una jornada que dej\u00f3 sus puertas abiertas para seguir el Martes con <strong>espacios de formaci\u00f3n<\/strong> con estudiantes de escuela electromec\u00e1nica, charlas y actividades vinculadas al sistema operativo Huayra y las netbooks de conectar igualdad en el laboratorio m\u00f3vil<\/p>\n\n\n\n<p>Participaron de la jornada: La Licenciada Andrea Garc\u00eda, Secretaria de Cooperaci\u00f3n Educativa y Acciones Prioritarias del Ministerio de Educaci\u00f3n de la Naci\u00f3n.<\/p>\n\n\n\n<p>El Licenciado Rub\u00e9n D&#8217;Audia Gerente General de EducAr<\/p>\n\n\n\n<p>Laura Penacca, Directora Nacional de Tecnolog\u00edas Educativa de EducAr<\/p>\n\n\n\n<p>El Director de Educaci\u00f3n Secundaria Agraria Gerardo Berchi<\/p>\n\n\n\n<p>La Inspectora Jefe Regional Florencia Ratto<\/p>\n\n\n\n<p>Concejales del F.D.T e Inspectores y Directores Distritales.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jjornnadavalida.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6150\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-jornada-de-educacion-que-dejo-fondos-compromiso-capacitacion-entrega-de-materiales-y-espacios-de-formacion\/attachment\/jjornnadavalida\/\" class=\"wp-image-6150\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jjornnadavalida.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jjornnadavalida.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jjornnadavalida.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jornadaaavalida.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6151\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jornadaaavalida.jpg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-jornada-de-educacion-que-dejo-fondos-compromiso-capacitacion-entrega-de-materiales-y-espacios-de-formacion\/attachment\/jornadaaavalida\/\" class=\"wp-image-6151\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jornadaaavalida.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jornadaaavalida.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/jornadaaavalida.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con la presencia de autoridades del Ministerio de Educaci\u00f3n de la Naci\u00f3n y La Provincia de Bs As Ameghino fue parte de una jornada ampliamente productiva para los niveles t\u00e9cnico-Agrarios Durante la ma\u00f1ana y parte de la tarde de este Lunes se fueron realizando tareas y anuncios en simultaneo en los niveles secundarios de ense\u00f1anza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,7,24,10,11,31,6,9,37],"tags":[],"class_list":["post-6140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-cultura","category-florentino-ameghino","category-gobierno","category-gobierno-provincial","category-importantes","category-interes-general","category-municipios","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/03\/JORNADA-VALIDA-PORTA.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6140"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6140\/revisions"}],"predecessor-version":[{"id":6152,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6140\/revisions\/6152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6141"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}