{"id":6405,"date":"2022-05-27T16:28:09","date_gmt":"2022-05-27T19:28:09","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6405"},"modified":"2022-05-31T12:33:07","modified_gmt":"2022-05-31T15:33:07","slug":"atencion-empresa-instalada-en-ameghino-necesita-profesional","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/atencion-empresa-instalada-en-ameghino-necesita-profesional\/","title":{"rendered":"Atencion:                       Empresa Instalada en  Ameghino necesita cubrir cargo."},"content":{"rendered":"\n<p>Se necesita persona para cubrir el cargo de <strong>\u00abTECNICO\/A EN SEGURIDAD E HIGIENE\u00bb<\/strong><\/p>\n\n\n\n<p><strong>Requisito<\/strong>: Ser mayor de edad- sexo <strong>Masculino <\/strong>o <strong>femenina<\/strong> sin necesidad de contar con experiencia previa .<\/p>\n\n\n\n<p>La convocatoria se realiza  para <strong>Empresa<\/strong> instalada en el Distrito de Ameghino.<\/p>\n\n\n\n<p> Para <strong>inscripci\u00f3n<\/strong>  y adquirir mas informaci\u00f3n comunicarse al tel. <strong>2478.468809.<\/strong>o dejar mje.<\/p>\n\n\n\n<p>\u00abLa tarea de un profesional <strong>t\u00e9cnico en seguridad e higiene <\/strong>es ejercer todas las acciones preventivas para poder evitar accidentes laborales\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se necesita persona para cubrir el cargo de \u00abTECNICO\/A EN SEGURIDAD E HIGIENE\u00bb Requisito: Ser mayor de edad- sexo Masculino o femenina sin necesidad de contar con experiencia previa . La convocatoria se realiza para Empresa instalada en el Distrito de Ameghino. Para inscripci\u00f3n y adquirir mas informaci\u00f3n comunicarse al tel. 2478.468809.o dejar mje. \u00abLa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,24,31,6,9,37],"tags":[],"class_list":["post-6405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/05\/OFERTA-LABORAL-VAL.jpg?fit=500%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6405"}],"version-history":[{"count":3,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6405\/revisions"}],"predecessor-version":[{"id":6417,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6405\/revisions\/6417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6406"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}