{"id":6476,"date":"2022-06-09T10:54:47","date_gmt":"2022-06-09T13:54:47","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6476"},"modified":"2022-06-09T10:54:50","modified_gmt":"2022-06-09T13:54:50","slug":"ameghino-testimonios-reflexion-y-empatia-acompanaron-la-presentacion-del-libro-de-gorenstein-nota","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/ameghino-testimonios-reflexion-y-empatia-acompanaron-la-presentacion-del-libro-de-gorenstein-nota\/","title":{"rendered":"Ameghino: testimonios- reflexi\u00f3n y empatia acompa\u00f1aron la presentaci\u00f3n del libro de Gorenstein.(nota)"},"content":{"rendered":"\n<p>Alejandro Gorenstein periodista y escritor present\u00f3 su libro acompa\u00f1ado  de dos mujeres de la comunidad brindando testimonios de vida que provocaron el silencio de los presentes sorprendidos por la realidad.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN3VALIDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6478\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6478\" class=\"wp-image-6478\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN3VALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN3VALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN3VALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/2GORENSTEIN-VALIDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6479\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/2GORENSTEIN-VALIDA.jpg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6479\" class=\"wp-image-6479\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/2GORENSTEIN-VALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/2GORENSTEIN-VALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/2GORENSTEIN-VALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>\u00abEl libro <strong>Mujeres Resilientes<\/strong> es el ultimo de mis trabajos pero hace mas de 10 a\u00f1os vengo publicando libros sobre este tema tanto de hombres como mujeres resilientes. Todos lo somos\u00bb -manifest\u00f3 Alejandro- \u00abEn este libro tomo como referencia a las mujeres, no porque sean mas resilientes que los hombres, sino porque son  mas expresivas, demostrativas y las que mas se contactan a trav\u00e9s de las redes o personalmente y son las que siempre est\u00e1n en la lucha, como <strong>madres de plaza de Mayo<\/strong>&#8211;<strong>las madres del dolor<\/strong>, <strong>las madres del paco, las que pierden a sus hijos, <\/strong>por eso me pareci\u00f3 que en este libro deb\u00eda resaltar esos temas, es un libro con <strong>testimonios reales <\/strong>y de cada lugar que visito me llevo historias\u00bb.<\/p>\n\n\n\n<p>\u00bfCuando dejamos de ser resilientes?- \u00bfque hacemos para buscar la salida y transformarnos ? \u00bf que contenido tiene el libro? \u00bfComo llega Alejandro a la zona? Las respuestas a estas preguntas en la siguiente nota.<\/p>\n\n\n\n<p><strong>NOTA A ALEJANDRO GORENSTEIN<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"ALEJANDRO GORENSTEIN. PERIODISTA ESCRITOR\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/MBzIbsNRsz8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN-VALIDA.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-6480\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN-VALIDA.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN-VALIDA.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEIN-VALIDA.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Alejandro Gorenstein periodista y escritor present\u00f3 su libro acompa\u00f1ado de dos mujeres de la comunidad brindando testimonios de vida que provocaron el silencio de los presentes sorprendidos por la realidad. \u00abEl libro Mujeres Resilientes es el ultimo de mis trabajos pero hace mas de 10 a\u00f1os vengo publicando libros sobre este tema tanto de hombres [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,7,2,24,6,9],"tags":[],"class_list":["post-6476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-cultura","category-destacadas","category-florentino-ameghino","category-interes-general","category-municipios"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GORENSTEINPORTADAVALIDA.jpg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6476"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6476\/revisions"}],"predecessor-version":[{"id":6481,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6476\/revisions\/6481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6477"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}