{"id":6516,"date":"2022-06-13T16:52:11","date_gmt":"2022-06-13T19:52:11","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6516"},"modified":"2022-06-21T20:57:55","modified_gmt":"2022-06-21T23:57:55","slug":"vivienda-incendiada-dejo-importantes-danos-materiales-personal-de-bomberos-y-policia-reanimaron-a-una-mascota","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/vivienda-incendiada-dejo-importantes-danos-materiales-personal-de-bomberos-y-policia-reanimaron-a-una-mascota\/","title":{"rendered":"VIVIENDA INCENDIADA DEJO IMPORTANTES DA\u00d1OS MATERIALES \u2013 PERSONAL DE BOMBEROS Y POLICIA REANIMARON A UNA MASCOTA"},"content":{"rendered":"\n<p>&nbsp;Vivienda de <strong>calle 7 y 18<\/strong> fue afectada por las llamas esta tarde.<\/p>\n\n\n\n<p>Un llamado a bomberos indicaba el incendio de una vivienda ubicada en calle 7 casi esquina 18 de Ameghino.<\/p>\n\n\n\n<p>En el lugar se encontraban sus habitantes, una mujer con sus dos hijos menores de edad.<\/p>\n\n\n\n<p>&nbsp;Por razones que a\u00fan no se precisaron comenz\u00f3 a arder la habitaci\u00f3n de la casa, provocando importantes da\u00f1os materiales y la asfixia de un felino que fue reanimado entre personal del cuerpo de bomberos y la comisaria Daniela Cionchi, en tanto la ambulancia del SAME asisti\u00f3 a la mama de los menores quien al detectar el siniestro sali\u00f3 r\u00e1pidamente con sus hijos de la vivienda pero al rescatar a uno de los menores de la habitaci\u00f3n &nbsp;fue alcanzada por el fuego recibiendo solo quemaduras en su cabello, pero encontr\u00e1ndose shokeada por la situaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/DA%C3%91OSPORTADAVALIDA-1.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6518\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6518\" class=\"wp-image-6518\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/DA%C3%91OSPORTADAVALIDA-1.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/DA%C3%91OSPORTADAVALIDA-1.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/DA%C3%91OSPORTADAVALIDA-1.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA4VALIDA.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6519\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6519\" class=\"wp-image-6519\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA4VALIDA.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA4VALIDA.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA4VALIDA.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA5VALIDA.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6520\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA5VALIDA.jpeg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6520\" class=\"wp-image-6520\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA5VALIDA.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA5VALIDA.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA5VALIDA.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><strong>DA\u00d1OS OCACIONADOS POR EL FUEGO<\/strong><\/figcaption><\/figure>\n\n\n\n<p>\u201cNo s\u00e9 bien que fue lo que provoc\u00f3 el incendio, ella me llamo dici\u00e9ndome que <strong>ard\u00eda la habitaci\u00f3n<\/strong> de su casa y la vi que sal\u00eda con sus dos hijos muy nerviosa, no se mas nada\u201d -cont\u00f3 a este medio una vecina que asisti\u00f3 a la moradora hasta que fue retirada por personal del hospital para ser evaluada.<\/p>\n\n\n\n<p>La llegada de dos dotaciones de bomberos logr\u00f3 <strong>controlar<\/strong> r\u00e1pidamente el fuego, aunque ya los da\u00f1os del interior eran <strong>importantes<\/strong> por lo que debieron levantar parte del techo para controlar el fuego entre el cielorraso y la chapa.<\/p>\n\n\n\n<p>&nbsp;Un p\u00e1rrafo aparte merece <strong>el rescate de una mascota<\/strong> ( una gata de los menores) que fue encontrada en el interior de la vivienda en estado profundo de <strong>asfixia <\/strong>y entre <strong>personal de bomberos<\/strong> y la oficial de la comisar\u00eda local <strong>Daniela Cionchi<\/strong> lograron reanimar dedic\u00e1ndole el tiempo y conocimientos adecuados, luego la trasladaron a una veterinaria para observaci\u00f3n y cuidados.<strong>  <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GATOVALIDO.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6521\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6521\" class=\"wp-image-6521\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GATOVALIDO.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GATOVALIDO.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/GATOVALIDO.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA6VALIDO.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" data-id=\"6522\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA6VALIDO.jpeg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6522\" class=\"wp-image-6522\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA6VALIDO.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA6VALIDO.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/VIVIENDA6VALIDO.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Trabajaron dos dotaciones de bomberos, polic\u00eda comunal y personal del SAME.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Vivienda de calle 7 y 18 fue afectada por las llamas esta tarde. Un llamado a bomberos indicaba el incendio de una vivienda ubicada en calle 7 casi esquina 18 de Ameghino. En el lugar se encontraban sus habitantes, una mujer con sus dos hijos menores de edad. &nbsp;Por razones que a\u00fan no se precisaron [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,24,31,6,9,34,37],"tags":[],"class_list":["post-6516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-policial","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/06\/DA%C3%91OSPORTADAVALIDA.jpeg?fit=667%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6516"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6516\/revisions"}],"predecessor-version":[{"id":6559,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6516\/revisions\/6559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6517"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}