{"id":6671,"date":"2022-08-05T14:04:51","date_gmt":"2022-08-05T17:04:51","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6671"},"modified":"2022-08-15T12:58:52","modified_gmt":"2022-08-15T15:58:52","slug":"ameghino-importante-incendio-en-zona-norte-de-la-ciudad-hizo-que-peligrar-viviendas-cercanas","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-importante-incendio-en-zona-norte-de-la-ciudad-hizo-que-peligrar-viviendas-cercanas\/","title":{"rendered":"Ameghino:               Importante incendio en zona Norte de la ciudad  hizo que peligrar viviendas cercanas."},"content":{"rendered":"\n<p><em><strong>Al momento del incendio las llamas hac\u00edan peligrar viviendas cercanas al predio.<\/strong><\/em><\/p>\n\n\n\n<p>Por razones que se desconocen, un predio ubicado en calle 14 e\/15 y 19 de la ciudad de Ameghino (conocido como quinta de Mayorga) fue totalmente<strong> cubierto por las<\/strong> <strong>llamas<\/strong> en pocos minutos.<\/p>\n\n\n\n<p>Vecinos del lugar alertaron a bomberos y polic\u00eda al ver que el fuego <strong>cubr\u00eda r\u00e1pidamente la totalidad del predio <\/strong>\u2013 que si bien es un amplio lote vac\u00edo- hay viviendas en la perimetral que corr\u00edan <strong>riesgos <\/strong>de ser alcanzadas por las llamas que se extingu\u00edan r\u00e1pidamente a ra\u00edz del viento del momento.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"289\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS2VALIDA.jpeg?resize=640%2C289&#038;ssl=1\" alt=\"\" data-id=\"6673\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6673\" class=\"wp-image-6673\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS2VALIDA.jpeg?resize=1024%2C462&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS2VALIDA.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS2VALIDA.jpeg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS2VALIDA.jpeg?w=1109&amp;ssl=1 1109w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"289\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg?resize=640%2C289&#038;ssl=1\" alt=\"\" data-id=\"6674\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6674\" class=\"wp-image-6674\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg?resize=1024%2C462&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSSSVALIDA.jpeg?w=1109&amp;ssl=1 1109w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Las tareas de dos dotaciones de bomberos lograron controlar la situaci\u00f3n hasta apaciguar las llamas y enfriar la zona perimetral.<\/p>\n\n\n\n<p>Al momento siguen las tareas de enfriamiento asegurando que no se propague ning\u00fan foco de incendio nuevamente, considerando que la situaci\u00f3n estar\u00eda controlada.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"288\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS3VALIDA.jpeg?resize=640%2C288&#038;ssl=1\" alt=\"\" data-id=\"6675\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6675\" class=\"wp-image-6675\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS3VALIDA.jpeg?resize=1024%2C460&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS3VALIDA.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS3VALIDA.jpeg?resize=768%2C345&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROS3VALIDA.jpeg?w=1113&amp;ssl=1 1113w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"288\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg?resize=640%2C288&#038;ssl=1\" alt=\"\" data-id=\"6676\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=6676\" class=\"wp-image-6676\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg?resize=1024%2C460&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg?resize=768%2C345&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSOTRAPORTADAVALIDA.jpeg?w=1113&amp;ssl=1 1113w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>En el lugar se encuentra operando personal de la polic\u00eda comunal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al momento del incendio las llamas hac\u00edan peligrar viviendas cercanas al predio. Por razones que se desconocen, un predio ubicado en calle 14 e\/15 y 19 de la ciudad de Ameghino (conocido como quinta de Mayorga) fue totalmente cubierto por las llamas en pocos minutos. Vecinos del lugar alertaron a bomberos y polic\u00eda al ver [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,24,31,6,9,34,37],"tags":[],"class_list":["post-6671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-policial","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BOMBEROSPORTADAVALIDA.jpeg?fit=1113%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6671"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6671\/revisions"}],"predecessor-version":[{"id":6677,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6671\/revisions\/6677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6672"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}