{"id":6679,"date":"2022-08-07T19:15:58","date_gmt":"2022-08-07T22:15:58","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=6679"},"modified":"2022-08-15T14:48:22","modified_gmt":"2022-08-15T17:48:22","slug":"blaquier-mejor-en-mi-pueblo-tuvo-su-segunda-edicion","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/blaquier-mejor-en-mi-pueblo-tuvo-su-segunda-edicion\/","title":{"rendered":"Blaquier                            \u201cMejor en mi pueblo\u201d tuvo su segunda edici\u00f3n."},"content":{"rendered":"\n<p><strong><em>Esta vez la propuesta cultural y art\u00edstica se realiz\u00f3 en la localidad de Blaquier.<\/em><\/strong><\/p>\n\n\n\n<p>Un Domingo que se present\u00f3 a pleno sol fue cubriendo el cielo de nubes dejando una tarde ventosa, aun as\u00ed, el evento que se organiz\u00f3 desde la Secretaria de cultura municipal \u201cMejor en mi pueblo\u201d se desarroll\u00f3 con todo lo que estaba previsto. <strong>Academias de baile, artesanos, entretenimientos para ni\u00f1os, stand de comidas y \u00e1reas municipales con folleter\u00eda de concientizaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>La propuesta fue lanzada hace unos meses con el objetivo de reunir a artistas locales y artesanos que tienen la oportunidad de mostrar su arte, sumado a la tarea de <strong>concientizaci\u00f3n <\/strong>e <strong>integraci\u00f3n<\/strong> de vecinos que se encuentran entre s\u00ed para recrearse en una tarde de domingo, aunque el clima no permiti\u00f3 la cantidad de p\u00fablico esperado, quienes asistieron pudieron disfrutar de un evento que seguir\u00e1 realiz\u00e1ndose en cada pueblo del distrito.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BLAQUIERVALIDA.jpeg?resize=412%2C308&#038;ssl=1\" alt=\"\" class=\"wp-image-6681\" width=\"412\" height=\"308\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BLAQUIERVALIDA.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BLAQUIERVALIDA.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BLAQUIERVALIDA.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 412px) 100vw, 412px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Esta vez la propuesta cultural y art\u00edstica se realiz\u00f3 en la localidad de Blaquier. Un Domingo que se present\u00f3 a pleno sol fue cubriendo el cielo de nubes dejando una tarde ventosa, aun as\u00ed, el evento que se organiz\u00f3 desde la Secretaria de cultura municipal \u201cMejor en mi pueblo\u201d se desarroll\u00f3 con todo lo que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,24,31,6,9,37],"tags":[],"class_list":["post-6679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/08\/BLAQUIER2VALIDAaaaaa.jpeg?fit=589%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6679"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6679\/revisions"}],"predecessor-version":[{"id":6682,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6679\/revisions\/6682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/6684"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}