{"id":7044,"date":"2022-11-04T12:55:39","date_gmt":"2022-11-04T15:55:39","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=7044"},"modified":"2022-11-08T07:51:48","modified_gmt":"2022-11-08T10:51:48","slug":"la-primera-mandataria-de-tejedor-expuso-en-la-mesa-de-intendentas","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/municipios\/la-primera-mandataria-de-tejedor-expuso-en-la-mesa-de-intendentas\/","title":{"rendered":"La primera mandataria de Tejedor expuso en la mesa de intendentas"},"content":{"rendered":"\n<p class=\"has-text-color has-very-dark-gray-color\">Fue en la XV Edici\u00f3n de la Expo <strong>Congreso Internacional de los Municipios y las Ciudades para Vivir Bien destinado a Gobiernos y Prestadores de Servicios P\u00fablicos<\/strong> que se realiz\u00f3 en el parque tem\u00e1tico Tecn\u00f3polis.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">La primera mandataria de Tejedor <strong>Maria Celia Gianini <\/strong>estuvo acompa\u00f1ada por las tambi\u00e9n intendentas <strong>Mar\u00eda Flor Dest\u00e9fanis<\/strong> del departamento de Santa Rosa \u2013 La Pampa- y <strong>Marisa Fassi<\/strong> de Ca\u00f1uelas \u2013 Buenos Aires- en donde se habl\u00f3 de los desaf\u00edos actuales de los gobiernos municipales, fortalezas y debilidades para afrontarlos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/11\/TECNOPOLIS-2VALIDA-1.jpg?resize=499%2C332&#038;ssl=1\" alt=\"\" class=\"wp-image-7049\" width=\"499\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/11\/TECNOPOLIS-2VALIDA-1.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/11\/TECNOPOLIS-2VALIDA-1.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption><strong>INT. MARIA C. GIANINI<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Durante el evento que fue inaugurado por el presidente de la Naci\u00f3n, <strong>Alberto Fern\u00e1ndez<\/strong>, el gobernador de la Provincia, <strong>Axel Kiciloff<\/strong>, y el presidente de la Federaci\u00f3n Argentina de Municipios e intendente de La Matanza, se presentaron tecnolog\u00edas, innovaciones, productos y nuevos servicios que permitir\u00e1n modernizar las ciudades y la gesti\u00f3n de gobierno, impulsar la transformaci\u00f3n de los municipios y territorios, e innovar en soluciones para las ciudades.<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en la XV Edici\u00f3n de la Expo Congreso Internacional de los Municipios y las Ciudades para Vivir Bien destinado a Gobiernos y Prestadores de Servicios P\u00fablicos que se realiz\u00f3 en el parque tem\u00e1tico Tecn\u00f3polis. La primera mandataria de Tejedor Maria Celia Gianini estuvo acompa\u00f1ada por las tambi\u00e9n intendentas Mar\u00eda Flor Dest\u00e9fanis del departamento de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,35,30,31,9,29],"tags":[],"class_list":["post-7044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carlos-tejedor","category-comunicacion","category-politicadirigencia","category-importantes","category-municipios","category-politica-estado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2022\/11\/TECNOPOLISVALIDA.jpg?fit=750%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=7044"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7044\/revisions"}],"predecessor-version":[{"id":7050,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7044\/revisions\/7050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/7046"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=7044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=7044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=7044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}