{"id":7345,"date":"2023-01-04T15:04:01","date_gmt":"2023-01-04T18:04:01","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=7345"},"modified":"2023-01-10T00:22:55","modified_gmt":"2023-01-10T03:22:55","slug":"ameghino-tellechea-volvio-a-pedir-licencia-despues-de-su-despido-de-la-funcion-publica","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/municipios\/ameghino-tellechea-volvio-a-pedir-licencia-despues-de-su-despido-de-la-funcion-publica\/","title":{"rendered":"Ameghino:                   Tellechea volvi\u00f3 a pedir licencia despu\u00e9s de su despido de la funci\u00f3n p\u00fablica."},"content":{"rendered":"\n<p class=\"has-text-color has-very-dark-gray-color\">En el mes de Septiembre el Intendente de Ameghino <strong>Calixto Tellechea<\/strong> solicit\u00f3 al concejo deliberante una licencia por <strong>tres meses<\/strong> -con goce de sueldo- por razones de <strong>salud<\/strong> que deb\u00eda atender.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Al d\u00eda siguiente de haberse aprobado la licencia por 90 d\u00edas en el concejo deliberante, el mismo <strong>Tellechea<\/strong> se expres\u00f3 en un <strong>comunicado oficial<\/strong> que se <strong>desped\u00eda<\/strong> del cargo de primer mandatario, dejando como <strong>interino<\/strong> a quien hoy ejerce como tal,  <strong>Nahuel Mitelbach<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">&nbsp;\u201cEl momento lleg\u00f3, esto lo pensamos desde el inicio de mi \u00faltima gesti\u00f3n, hay que dejarles paso a las generaciones m\u00e1s j\u00f3venes y darle oxigenaci\u00f3n a la gesti\u00f3n, por lo que acompa\u00f1ar\u00e9 a Nahuel en esta <strong>transici\u00f3n<\/strong> durante los tres meses y hasta el <strong>fin de mi mandato<\/strong>, debo ocuparme de un tema de salud pendiente, nada grave, pero el que debo atender\u201d -asegur\u00f3 Tellechea-<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">En la primera sesi\u00f3n del a\u00f1o realizada el pasado martes 3 de Enero se presenta un nuevo pedido de <strong>licencia<\/strong> del intendente electo Calixto Tellechea por <strong>30 d\u00edas<\/strong> mas y con goce de sueldo, aun a sabiendas que el mandatario interino tambi\u00e9n cobra sus haberes.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">\u201cNosotros no ponemos en tela de juicio la salud del intendente Tellechea ni la cirug\u00eda que debe realizarse, lo que no podemos entender es c\u00f3mo, si se despidi\u00f3 de la funci\u00f3n hasta fin de su mandato y habi\u00e9ndose cumplido la licencia de tres meses, hoy vuelve a solicitar otra, entendemos \u2013por las expresiones oficiales- que Nahuel Mittelbach debe cumplir la gesti\u00f3n de Tellechea\u201d expresaron en la sesi\u00f3n los concejales de la oposici\u00f3n-<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">\u201cEstamos hablando de <strong>dos millones<\/strong> de pesos que le cuesta al pueblo de Florentino Ameghino el hecho de que haya dos intendentes cobrando sueldo\u201d- agregaron-<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">En tanto el bloque oficialista se refiri\u00f3 a la salud del intendente y a la poca <strong>sensibilidad<\/strong> del bloque opositor a un tema de salud \u201cNo se sabe si el Intendente vuelve o no, eso se ver\u00e1 de acuerdo a como se desarrolle su tratamiento\u201d \u2013expresaron- dichos que se <strong>contraponen<\/strong> con el comunicado del intendente \u2013 hasta el momento <strong>no desmentido<\/strong>&#8211; donde anunci\u00f3 su retiro definitivo<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/01\/COMUNICADOOFICIAL-VALIDO.jpg?resize=375%2C375&#038;ssl=1\" alt=\"\" class=\"wp-image-7346\" width=\"375\" height=\"375\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/01\/COMUNICADOOFICIAL-VALIDO.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/01\/COMUNICADOOFICIAL-VALIDO.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/01\/COMUNICADOOFICIAL-VALIDO.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><figcaption><strong>EMITIDO EL PASADO 21 DE SEPTIEMBRE<\/strong><\/figcaption><\/figure>\n\n\n\n<h2 class=\"has-very-dark-gray-color has-text-color wp-block-heading\" id=\"jsc_c_3ft\"><a href=\"https:\/\/www.facebook.com\/municipalidadameghino?__cft__[0]=AZXk_MWxZp4M5Vx3YRAN4IRYHSgfwAGYZKd5hof6wYoACiW6YCnCYbhLKrnTCb2CUEMNTghdalazccrxm1MEDizota2gqPf2k9Rs9R9JKai3dXe4HtTTztr2rAVTPC7HOuIv0AW9KDNuhc6PVQ956YFcIJ3gTuMacJBY_4aE7HPKDd4x3LL1DK0y6B048xz76CI&amp;__tn__=-UC%2CP-R\"><strong>Municipalidad de Florentino Ameghino<\/strong><\/a><\/h2>\n\n\n\n<p class=\"has-text-color has-background has-very-dark-gray-color has-cyan-bluish-gray-background-color\"><a href=\"https:\/\/www.facebook.com\/municipalidadameghino\/posts\/397449112562698?__cft__[0]=AZXk_MWxZp4M5Vx3YRAN4IRYHSgfwAGYZKd5hof6wYoACiW6YCnCYbhLKrnTCb2CUEMNTghdalazccrxm1MEDizota2gqPf2k9Rs9R9JKai3dXe4HtTTztr2rAVTPC7HOuIv0AW9KDNuhc6PVQ956YFcIJ3gTuMacJBY_4aE7HPKDd4x3LL1DK0y6B048xz76CI&amp;__tn__=%2CO%2CP-R\"><\/a>&nbsp;&nbsp;\u00b7&nbsp;COMUNICADO OFICIAL  Despu\u00e9s de casi 7 a\u00f1os como Intendente de Florentino Ameghino, Calixto Tellechea emprende su retirada de la funci\u00f3n p\u00fablica. Mediante un comunicado oficial en el d\u00eda de hoy, el Intendente ha manifestado su convicci\u00f3n de darle paso a las nuevas generaciones al frente del Municipio y principalmente atender sus temas pendientes de salud. Quien asume en su lugar, a partir del 3 de octubre, es Nahuel Mittelbach, abogado, de 28 a\u00f1os de edad, quien fue Secretario de Gobierno y Hacienda (2018\/19) y actualmente es Concejal. Esto se condice con lo afirmado por Tellechea en varias ocasiones, acerca de la necesidad de que una nueva generaci\u00f3n de dirigentes locales asuma el liderazgo del Distrito para darle continuidad y oxigenaci\u00f3n a la gesti\u00f3n iniciada en 2015. Tellechea deja el cargo tras dos mandatos consecutivos marcados por hitos como el ordenamiento econ\u00f3mico y financiero del Municipio, la revalorizaci\u00f3n de los empleados municipales, la jerarquizaci\u00f3n del sistema de salud y una gran inversi\u00f3n en infraestructura hospitalaria, la profesionalizaci\u00f3n del \u00e1rea de bromatolog\u00eda y zoonosis, la puesta en marcha de un nuevo geri\u00e1trico y el primer Centro de D\u00eda para personas con discapacidad, la inversi\u00f3n del fondo educativo en infraestructura escolar y la construcci\u00f3n de la Nueva Escuela T\u00e9cnica, la implementaci\u00f3n del primer programa de reciclaje, la ampliaci\u00f3n de servicios b\u00e1sicos como red de gas, cloacas y agua potable -que hoy alcanzan a casi el 100% de la poblaci\u00f3n-, la mejora del alumbrado p\u00fablico, la creaci\u00f3n y puesta en valor de espacios p\u00fablicos, la construcci\u00f3n de ciclov\u00edas, adem\u00e1s de una gesti\u00f3n amplia a lo largo de estos a\u00f1os en ofertas culturales, deportivas y recreativas para toda la comunidad. El actual Intendente ha manifestado su voluntad de ocuparse prioritariamente de su salud, para lo que estar\u00e1 de licencia durante los pr\u00f3ximos tres meses, tiempo que dedicar\u00e1 tambi\u00e9n a acompa\u00f1ar la transici\u00f3n con el Intendente interino Nahuel Mittelbach, quien luego continuar\u00e1 hasta el cumplimiento del mandato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mes de Septiembre el Intendente de Ameghino Calixto Tellechea solicit\u00f3 al concejo deliberante una licencia por tres meses -con goce de sueldo- por razones de salud que deb\u00eda atender. Al d\u00eda siguiente de haberse aprobado la licencia por 90 d\u00edas en el concejo deliberante, el mismo Tellechea se expres\u00f3 en un comunicado oficial [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35,24,31,9],"tags":[],"class_list":["post-7345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-florentino-ameghino","category-importantes","category-municipios"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/01\/MUNIVALIDA.jpeg?fit=877%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=7345"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7345\/revisions"}],"predecessor-version":[{"id":7349,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7345\/revisions\/7349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/7347"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=7345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=7345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=7345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}