{"id":7510,"date":"2023-02-03T17:46:07","date_gmt":"2023-02-03T20:46:07","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=7510"},"modified":"2023-02-13T21:22:58","modified_gmt":"2023-02-14T00:22:58","slug":"festival-de-pasteur-que-ofrecen-las-cinco-noches-del-evento-nota-a-guillermo-de-vega","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/festival-de-pasteur-que-ofrecen-las-cinco-noches-del-evento-nota-a-guillermo-de-vega\/","title":{"rendered":"\u00abComenz\u00f3 el Festival de Pasteur\u00bb                                \u00bfQue ofrecen las cinco noches del evento?  (nota a Guillermo de Vega)"},"content":{"rendered":"\n<p class=\"has-text-color has-very-dark-gray-color\">El festival competitivo de Pasteur que transita su 31\u00b0 edici\u00f3n redobl\u00f3 la apuesta este a\u00f1o con <strong>cinco noches<\/strong> consecutivas de canto, danza y n\u00fameros art\u00edsticos regionales y nacionales.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Este jueves 2 de febrero la apertura oficial se dio en el marco de un predio colmado de p\u00fablico a pesar de ser un d\u00eda de semana, que presenci\u00f3 las competencias de canto y danza provenientes de diferentes puntos del territorio bonaerense y un cierre con <strong>Lucia Modad<\/strong> y el estelar grupo musical \u201c<strong>Destino San Javier\u201d <\/strong>consagraci\u00f3n Cosquin 2023<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"288\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteurvalida.jpeg?resize=640%2C288&#038;ssl=1\" alt=\"\" data-id=\"7512\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=7512\" class=\"wp-image-7512\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteurvalida.jpeg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteurvalida.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteurvalida.jpeg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteurvalida.jpeg?w=1110&amp;ssl=1 1110w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"288\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg?resize=640%2C288&#038;ssl=1\" alt=\"\" data-id=\"7513\" data-full-url=\"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg\" data-link=\"https:\/\/www.labrujulaweb.com.ar\/blog\/?attachment_id=7513\" class=\"wp-image-7513\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/pasteur-valida1.jpeg?w=1110&amp;ssl=1 1110w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><strong>LUCIA MODAD-DESTINO SAN JAVIER<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Hoy viernes 3 de Febrero, contin\u00faan los n\u00fameros en escenario cerrando la velada <strong>Adri\u00e1n Caminos<\/strong> (el trovador) y <strong>Horacio Guaran\u00ed,<\/strong> hijo del exponente cantautor de folklore Nacional.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">El s\u00e1bado se presentar\u00e1n <strong>\u201cPor tres Folclore\u201d <\/strong>(revelaci\u00f3n de las pe\u00f1as de Cosquin 23)<strong> \u201cLos Pampeanos y \u201cLos Caldenes\u201d<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Por otro lado, el <strong>domingo 5 de febrero<\/strong>, Pasteur vivir\u00e1 su \u00faltimo d\u00eda de festejos y la entrada al festival ser\u00e1 <strong>libre y gratuita.<\/strong> La jornada se iniciar\u00e1 a las 9.30 horas sobre Avenida Mitre con un gran desfile institucional de Emprendados y maquinaria agr\u00edcola, mientras que <strong>\u201cTrio Pasteur\u201d y \u201cLos Yupanqui\u201d <\/strong>ser\u00e1n los encargados de bajar el tel\u00f3n musical.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">A su vez, durante el desarrollo del festival los concurrentes disfrutan del patio de comidas, cantinas y feria de artesanos y microemprendedores.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>NOTA AL PTE DE LA COMISION DEL FESTIVAL GUILLERMO DE VEGA.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Guillermo De Vega Pte. Comisi\u00f3n Festival de Paster.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/n9kf2zDOdc8?start=4&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"288\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTRVALD3.jpeg?resize=640%2C288&#038;ssl=1\" alt=\"\" class=\"wp-image-7514\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTRVALD3.jpeg?resize=1024%2C460&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTRVALD3.jpeg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTRVALD3.jpeg?resize=768%2C345&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTRVALD3.jpeg?w=1113&amp;ssl=1 1113w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El festival competitivo de Pasteur que transita su 31\u00b0 edici\u00f3n redobl\u00f3 la apuesta este a\u00f1o con cinco noches consecutivas de canto, danza y n\u00fameros art\u00edsticos regionales y nacionales. Este jueves 2 de febrero la apertura oficial se dio en el marco de un predio colmado de p\u00fablico a pesar de ser un d\u00eda de semana, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,31,6,37],"tags":[],"class_list":["post-7510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-importantes","category-interes-general","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/02\/PASTEUR-VALI2.jpeg?fit=1110%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=7510"}],"version-history":[{"count":3,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7510\/revisions"}],"predecessor-version":[{"id":7517,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/7510\/revisions\/7517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/7511"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=7510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=7510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=7510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}