{"id":8042,"date":"2023-05-12T11:39:03","date_gmt":"2023-05-12T14:39:03","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=8042"},"modified":"2023-05-16T12:34:56","modified_gmt":"2023-05-16T15:34:56","slug":"atencion-estudiantes-de-ameghino-transporte-gratuito-para-el-proximo-fin-de-semana-largo-desde-junin-como-acceder","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/atencion-estudiantes-de-ameghino-transporte-gratuito-para-el-proximo-fin-de-semana-largo-desde-junin-como-acceder\/","title":{"rendered":"\u00a1Atenci\u00f3n estudiantes de Ameghino!-Transporte gratuito para el pr\u00f3ximo fin de semana largo desde Junin! \u00bfC\u00f3mo acceder?"},"content":{"rendered":"\n<p class=\"has-text-color has-very-dark-gray-color\"><strong><em>A trav\u00e9s del programa \u201cFinde largo en mi pueblo\u201d el municipio pondr\u00e1 a disposici\u00f3n sus combis para brindar a posibilidad a los estudiantes de visitar su ciudad natal los fines de semana largos. La inscripci\u00f3n abre este viernes y en esta oportunidad es desde la ciudad de Junin.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">El pr\u00f3ximo es el de 25 de mayo por lo que se detalla el recorrido y d\u00edas y horarios de partida.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>Recorrido<\/strong>:<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>JUN\u00cdN<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong><em>D\u00cdA DE SALIDA<\/em><\/strong>: MI\u00c9RCOLES 24 DE MAYO<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">HORARIO: 20 hs<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">LUGAR: LA TERMINAL DE \u00d3MNIBUS DE JUN\u00cdN<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>REGRESO DE AMEGHINO<\/strong> EL 28\/05 A LAS 20 hs.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>LINCOLN<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong><em>D\u00cdA DE SALIDA<\/em><\/strong>: MI\u00c9RCOLES 24 DE MAYO<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">HORARIO: 21 hs<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">LUGAR: TERMINAL DE \u00d3MNIBUS LINCOLN<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>REQUISITO PARA LA INSCRIPCI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Enviar constancia de alumno regular de la carrera del a\u00f1o 2023.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>\u00bfQUIENES TIENEN <\/strong><strong>PRIORIDAD?:<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Estudiantes que no utilizaron el transporte municipal el feriado de semana santa.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>Cupos limitados<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Los cupos ser\u00e1n limitados de acuerdo a los asientos disponibles en las combis, y se otorgar\u00e1n por orden de inscripci\u00f3n. Los estudiantes que queden afuera del primer viaje, tendr\u00e1n prioridad para siguiente fin de semana largo.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>Cancelaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Los estudiantes que confirmen lugar y lo cancelen con menos de 48 hs. de anticipaci\u00f3n, perder\u00e1n la prioridad para los viajes siguientes.<\/p>\n\n\n\n<p><strong>La inscripci\u00f3n abre HOY viernes 12 a las 8Hs.<\/strong><\/p>\n\n\n\n<p class=\"has-text-color has-background has-very-dark-gray-color has-vivid-green-cyan-background-color\">Para inscribirte comun\u00edcate de <strong>7 a 13 horas al 3388670217.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s del programa \u201cFinde largo en mi pueblo\u201d el municipio pondr\u00e1 a disposici\u00f3n sus combis para brindar a posibilidad a los estudiantes de visitar su ciudad natal los fines de semana largos. La inscripci\u00f3n abre este viernes y en esta oportunidad es desde la ciudad de Junin. El pr\u00f3ximo es el de 25 de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,29],"tags":[],"class_list":["post-8042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-politica-estado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-04-02-at-20.17.39-1.jpeg?fit=1600%2C721&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=8042"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8042\/revisions"}],"predecessor-version":[{"id":8045,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8042\/revisions\/8045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/8043"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=8042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=8042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=8042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}