{"id":8373,"date":"2023-06-28T20:15:22","date_gmt":"2023-06-28T23:15:22","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=8373"},"modified":"2023-07-03T12:48:01","modified_gmt":"2023-07-03T15:48:01","slug":"ameghino-allanamiento-con-secuestro-de-armas-y-sustancias","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/ameghino-allanamiento-con-secuestro-de-armas-y-sustancias\/","title":{"rendered":"Ameghino: Allanamiento con secuestro de armas y sustancias"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color\">&nbsp;A ra\u00edz de Allanamiento en un domicilio de la planta urbana de Ameghino realizado por personal de la <strong>Jefatura de&nbsp; Polic\u00eda Comunal Ameghino,&nbsp;<\/strong> juntamente con <strong>G.A.D<\/strong> (Grupo de apoyo Departamental) Lincoln y <strong>C.P.R<\/strong> (Comando Patrulla Rural) &nbsp;F. Ameghino, donde habita una persona de <strong>sexo masculino de 18 a\u00f1os de edad<\/strong>, se procedi\u00f3 al secuestro de un arma de fuego, calibre 38, tipo revolver, marca detectivo, cromada; un arma de fuego, marca Smith wessehn, tipo revolver, calibre 38; un arma de fuego,&nbsp; tipo revolver, marca Destroyer, calibre 38; y un arma de fuego, plateado, calibre 38, tipo revolver, con cachas pl\u00e1sticas, color negra, sin marca visible, con sistema de carga quebrada, y ocho municiones calibre 38.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">&nbsp; Se inicia Investigaci\u00f3n Penal Preparatoria caratulada <strong>TENENCIA ILEGAL DE ARMA DE FUEGO.<\/strong> Intervino <strong>Ayudant\u00eda Fiscal Ameghino y UFIJ N\u00b0 1 Dpto. Judicial Jun\u00edn.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Por otra parte, se procedi\u00f3 al secuestro de <strong>sustancias verde parduzca s\u00edmil marihuana<\/strong>, arrojando un guarismo de 36 g, inici\u00e1ndose Investigaci\u00f3n Penal, caratulada <strong>INFRACCION LEY 23.737<\/strong> intervenci\u00f3n <strong>Fiscal\u00eda de Estupefacientes Dpto. Judicial Jun\u00edn.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Para con el imputado se cumplen recaudos legales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"419\" height=\"500\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/06\/MARUHUVALIDA.jpeg?resize=419%2C500&#038;ssl=1\" alt=\"\" class=\"wp-image-8375\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/06\/MARUHUVALIDA.jpeg?w=419&amp;ssl=1 419w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/06\/MARUHUVALIDA.jpeg?resize=251%2C300&amp;ssl=1 251w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;A ra\u00edz de Allanamiento en un domicilio de la planta urbana de Ameghino realizado por personal de la Jefatura de&nbsp; Polic\u00eda Comunal Ameghino,&nbsp; juntamente con G.A.D (Grupo de apoyo Departamental) Lincoln y C.P.R (Comando Patrulla Rural) &nbsp;F. Ameghino, donde habita una persona de sexo masculino de 18 a\u00f1os de edad, se procedi\u00f3 al secuestro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,34],"tags":[],"class_list":["post-8373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-policial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/06\/ARMASSSVALIDA.jpeg?fit=709%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=8373"}],"version-history":[{"count":3,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8373\/revisions"}],"predecessor-version":[{"id":8405,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8373\/revisions\/8405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/8374"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=8373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=8373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=8373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}