{"id":8449,"date":"2023-07-11T13:58:22","date_gmt":"2023-07-11T16:58:22","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=8449"},"modified":"2023-07-17T22:37:08","modified_gmt":"2023-07-18T01:37:08","slug":"los-kits-del-plan-qunita-bonaerense-son-fabricados-en-las-carceles-todos-los-municipios-lo-recibiran","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/los-kits-del-plan-qunita-bonaerense-son-fabricados-en-las-carceles-todos-los-municipios-lo-recibiran\/","title":{"rendered":"los kits del plan Qunita bonaerense son fabricados en las c\u00e1rceles.todos los municipios lo recibir\u00e1n."},"content":{"rendered":"\n<p class=\"has-black-color has-text-color\">El Gobierno provincial anunci\u00f3 que el programa&nbsp;<strong><a href=\"https:\/\/infocielo.com\/plan-a14357\"><strong>Qunita<\/strong><\/a><\/strong><strong>&nbsp;<\/strong><strong>bonaerense<\/strong>&nbsp;ser\u00e1 \u00abuniversal\u00bb para &nbsp;todos los reci\u00e9n nacidos en hospitales p\u00fablicos de la&nbsp;<strong><a href=\"https:\/\/infocielo.com\/provincia-buenos-aires\">provincia de Buenos Aires<\/a><\/strong>, quienes recibir\u00e1n no solamente el kit para el cuidado y la crianza del beb\u00e9, sino tambi\u00e9n acceso a diferentes etapas de la salud de la madre y el ni\u00f1o o ni\u00f1a, como la vacunaci\u00f3n gratuita, m\u00e9todos anticonceptivos post parto y controles de salud pedi\u00e1tricos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Cabe recordar que,&nbsp;hasta el momento, el plan Qunita bonaerense era \u00fanicamente para las madres beneficiarias del Asignaci\u00f3n por Embarazo de la ANSES que solicitaran el programa. De esta manera, comenzar\u00e1 a entregarse en los hospitales p\u00fablicos de la Provincia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Uno de los puntos destacados, adem\u00e1s, tiene que ver con que&nbsp;<strong>el kit completo de Qunita es fabricado en c\u00e1rceles de la provincia de Buenos Aires por presidiarios, bajo el estricto control de la Comisi\u00f3n de Investigaciones Cient\u00edficas (CIC)<\/strong>&nbsp;para garantizar la calidad de los productos finales.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">En total trabajan m\u00e1s de 600 internos de cuatro c\u00e1rceles provinciales, quienes reciben capacitaci\u00f3n por parte del Ministerio de Trabajo y egresar\u00e1n como t\u00e9cnicos textiles en carpinter\u00eda.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">\u00abAxel Kicillof ya inaugur\u00f3 los cuatro polos industriales que producen Quinta: Olmos, la c\u00e1rcel de mujeres de Los Hornos, el pabell\u00f3n de diversidad de Florencio Varela y la c\u00e1rcel de pre egreso de San Mart\u00edn; esas cuatro producen el Qunita.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">&nbsp;De esta manera el Qunita logr\u00f3 el milagro de dignificar a seres humanos que est\u00e1n privados de su libertad.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\"><strong>A continuacion el kit completo que incluye el plan.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"344\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/07\/QUNITAVALIDO.jpeg?resize=640%2C344&#038;ssl=1\" alt=\"\" class=\"wp-image-8450\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/07\/QUNITAVALIDO.jpeg?w=931&amp;ssl=1 931w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/07\/QUNITAVALIDO.jpeg?resize=300%2C161&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/07\/QUNITAVALIDO.jpeg?resize=768%2C412&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno provincial anunci\u00f3 que el programa&nbsp;Qunita&nbsp;bonaerense&nbsp;ser\u00e1 \u00abuniversal\u00bb para &nbsp;todos los reci\u00e9n nacidos en hospitales p\u00fablicos de la&nbsp;provincia de Buenos Aires, quienes recibir\u00e1n no solamente el kit para el cuidado y la crianza del beb\u00e9, sino tambi\u00e9n acceso a diferentes etapas de la salud de la madre y el ni\u00f1o o ni\u00f1a, como la vacunaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,31,6,29,36],"tags":[],"class_list":["post-8449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno-provincial","category-importantes","category-interes-general","category-politica-estado","category-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/07\/QUNITA1VALID.jpg?fit=668%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=8449"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8449\/revisions"}],"predecessor-version":[{"id":8452,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8449\/revisions\/8452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/8451"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=8449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=8449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=8449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}