{"id":8607,"date":"2023-08-08T22:48:11","date_gmt":"2023-08-09T01:48:11","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=8607"},"modified":"2023-08-10T21:01:32","modified_gmt":"2023-08-11T00:01:32","slug":"la-casa-de-la-provincia-de-buenos-aires-se-construira-en-ameghino-que-significa-contar-con-ese-espacio","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/la-casa-de-la-provincia-de-buenos-aires-se-construira-en-ameghino-que-significa-contar-con-ese-espacio\/","title":{"rendered":"La \u201cCasa de la Provincia de Buenos Aires\u201d se construir\u00e1 en  Ameghino \u00bfQue significa contar con ese espacio?"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color\">Se conoci\u00f3 esta tarde la noticia de que finalmente se comenzar\u00e1 a construir <strong>\u201cLa casa de la Provincia\u201d <\/strong>en la ciudad cabecera del distrito de Ameghino.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Lo confirm\u00f3 a este medio en una comunicaci\u00f3n telef\u00f3nica el precandidato a Intendente y <strong>Director Provincial de escuelas Agrarias Gerardo Berchi<\/strong> quien ademas manifest\u00f3 que el mismo <strong>Gobernador Axel Kicillof<\/strong> fue quien se comprometi\u00f3 a que fuera una realidad en breve.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">\u201cLa Casa de la Provincia funcionar\u00e1 como centro de tr\u00e1mites de organismos provinciales y generar\u00e1 trabajo para m\u00e1s ciudadanos y el gobernador lo hace con la certeza de que el estado tiene que estar cerca y al servicio de los vecinos\u201d-agreg\u00f3 Geri.<br><br>\u201cEl edificio de m\u00e1s de <strong>700 metros cuadrados<\/strong> contar\u00e1 con distintas oficinas, entre ellas, tramites de Ioma, de educaci\u00f3n, cultura, del Ministerio de las mujeres.<br>Tambi\u00e9n podremos tramitar la personer\u00eda jur\u00eddica y todos los tr\u00e1mites relacionados con habilitaciones productivos y comerciales\u201d.<br><br>\u201cEn cada una de las Casas de la Provincia conviven distintos servicios, organizados en delegaciones tales como Direcci\u00f3n General de Cultura y Educaci\u00f3n, Ministerio de Seguridad, Ministerio de Agroindustria, Bolet\u00edn Oficial y Registro de las Personas\u201d<br><br>\u201cTambi\u00e9n estas casas albergar\u00e1n las delegaciones de los ministerios de Salud, y de Desarrollo Social; Juzgado Administrativo de Faltas de Tr\u00e1nsito; IPS Previsi\u00f3n Social; IPS Turismo Social; Subsecretar\u00eda de Turismo; IOMA y ARBA . Tambi\u00e9n delegaci\u00f3n del ministerio de Trabajo y del Ministerio de las mujeres\u201d-concluy\u00f3 Berchi-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se conoci\u00f3 esta tarde la noticia de que finalmente se comenzar\u00e1 a construir \u201cLa casa de la Provincia\u201d en la ciudad cabecera del distrito de Ameghino. Lo confirm\u00f3 a este medio en una comunicaci\u00f3n telef\u00f3nica el precandidato a Intendente y Director Provincial de escuelas Agrarias Gerardo Berchi quien ademas manifest\u00f3 que el mismo Gobernador Axel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,11,31,6,9,29,37],"tags":[],"class_list":["post-8607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-gobierno-provincial","category-importantes","category-interes-general","category-municipios","category-politica-estado","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/08\/CASA-DE-LA-PCIAVALIDA.jpeg?fit=701%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=8607"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8607\/revisions"}],"predecessor-version":[{"id":8609,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8607\/revisions\/8609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/8608"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=8607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=8607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=8607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}