{"id":8897,"date":"2023-10-02T17:16:32","date_gmt":"2023-10-02T20:16:32","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=8897"},"modified":"2023-10-04T08:48:14","modified_gmt":"2023-10-04T11:48:14","slug":"para-las-entidades-del-campo-el-debate-presidencial-no-conformo-y-quedaron-con-gusto-a-poco","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/para-las-entidades-del-campo-el-debate-presidencial-no-conformo-y-quedaron-con-gusto-a-poco\/","title":{"rendered":"Para las entidades del campo, el debate presidencial no conform\u00f3 y quedaron \u201ccon gusto a poco\u201d"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color\">El primero de los debates entre los candidatos presidenciales realizado en la ciudad de Santiago del Estero no conform\u00f3 a los referentes de las <strong>entidades gremiales<\/strong> del sector agropecuario, como tampoco a actores de las cadenas productivas, que seg\u00fan dijeron luego de la realizaci\u00f3n del mismo, la sensaci\u00f3n es \u201cgusto a poco\u201d.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">En relaci\u00f3n a esto, el presidente de la Federaci\u00f3n Agraria Argentina, <strong>Carlos Achetoni,<\/strong> manifest\u00f3 su impresi\u00f3n: \u201cNinguno aludi\u00f3 qu\u00e9 es lo que van a hacer con el campo, y es esperable que tampoco lo hagan la semana pr\u00f3xima\u201d<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">En el mismo sentido, <strong>Elbio Laucirica,<\/strong> presidente de Coninagro, que fue muy cr\u00edtico del debate. Sobre el mismo, dijo que \u201csolo se hicieron acusaciones mutuas\u201d.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Por su parte, el presidente de Maizar, la cadena de producci\u00f3n e industrializaci\u00f3n del ma\u00edz, <strong>Pedro Vigneau,<\/strong> dijo que se qued\u00f3 \u201ccon gusto a poco\u201d, ya que esperaba propuestas m\u00e1s claras para el sector.<\/p>\n\n\n\n<p><strong>Fuente: Bichos de campo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primero de los debates entre los candidatos presidenciales realizado en la ciudad de Santiago del Estero no conform\u00f3 a los referentes de las entidades gremiales del sector agropecuario, como tampoco a actores de las cadenas productivas, que seg\u00fan dijeron luego de la realizaci\u00f3n del mismo, la sensaci\u00f3n es \u201cgusto a poco\u201d. En relaci\u00f3n a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[31,6,33],"tags":[],"class_list":["post-8897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-importantes","category-interes-general","category-rural"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/10\/debate-750x375WVALID.jpg?fit=937%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=8897"}],"version-history":[{"count":3,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8897\/revisions"}],"predecessor-version":[{"id":8901,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/8897\/revisions\/8901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/8898"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=8897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=8897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=8897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}