{"id":9262,"date":"2023-12-16T18:04:28","date_gmt":"2023-12-16T21:04:28","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=9262"},"modified":"2023-12-18T14:22:23","modified_gmt":"2023-12-18T17:22:23","slug":"la-viajera-ameghinense-que-pedaleando-recorrio-argentinabrasil-y-paraguay-hoy-regreso-con-su-bici-y-su-perra-nota","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/la-viajera-ameghinense-que-pedaleando-recorrio-argentinabrasil-y-paraguay-hoy-regreso-con-su-bici-y-su-perra-nota\/","title":{"rendered":"La viajera Ameghinense que pedaleando recorri\u00f3 Argentina,Brasil y Paraguay, hoy regres\u00f3 con su bici y su perra (nota)"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c1401d3f7f8ad7b6c5e5590e3c5cf47a\">Ella es <strong>Flor Mor\u00f3n, <\/strong>24 a\u00f1os, gastron\u00f3mica de profesi\u00f3n, hace tres a\u00f1os parti\u00f3 de su casa en Ameghino como mochilera a cumplir con su objetivo, recorrer el pais, llegar a Brasil, viviendo de su arte.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8604be2c2defd606553089419981a74b\">\u00abSiempre dije que un dia quer\u00eda hacer esta experiencia, cuando me recib\u00ed,<strong> agarre una mochila, una bolsa de dormir, mis malabares y me fui hasta Junin<\/strong>, desde all\u00ed empece como mochilera, ya en Brasil un amigo me convenci\u00f3 de la bicicleta y as\u00ed comenc\u00e9 una nueva experiencia pedaleando, luego vinieron las mascotas, conoc\u00ed a un gato y luego a mi perra \u00abrenga dinamita\u00bb que es Brasilera y hoy regres\u00f3 conmigo\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-id=\"9266\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLOR-MORONVALIS-1.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" class=\"wp-image-9266\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLOR-MORONVALIS-1.jpg?w=888&amp;ssl=1 888w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLOR-MORONVALIS-1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLOR-MORONVALIS-1.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"9267\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMORON2VALID-1.jpeg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-9267\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMORON2VALID-1.jpeg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMORON2VALID-1.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMORON2VALID-1.jpeg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-id=\"9268\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMOVALIA.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" class=\"wp-image-9268\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMOVALIA.jpg?w=888&amp;ssl=1 888w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMOVALIA.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORMOVALIA.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a1dfc3952fd9f3bac9e544d216330fba\">\u00abFue una experiencia enriquecedora, trabajaba haciendo arte callejero, como malabarista, hice artesan\u00edas y con eso logr\u00e9 adquirir muchas cosas e ir viviendo,<strong>me gusta la autogesti\u00f3n, <\/strong>nunca quise que mi familia me enviara dinero, quer\u00eda poder sola y lo logr\u00e9\u00bb. -cuenta la viajera-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d4b41737930545184b5e7d2ac9cd95e4\">\u00abEn Febrero <strong>pienso volver a pedalear a las rutas<\/strong> ya que Uruguay sera mi pr\u00f3ximo destino y luego llegar a Canad\u00e1\u00bb -asegura-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5c9a9185b6933b0be2c733293da66f80\">As\u00ed Flor comienza a contar su historia en una nota a este medio, a la que luego sumamos a su mam\u00e1 <strong>Laura Barb\u00e9 <\/strong>quien manifest\u00f3 que \u00abFlor cuando se recibi\u00f3 me dijo: \u00abac\u00e1 tenes el titulo, ahora me voy\u00bb \u00abNo es f\u00e1cil, pero siempre respetamos las decisiones de nuestros hijos, ella quiso esto desde chiquita y la veo feliz, hoy, a pesar de las preocupaciones, me siento plena de que pueda hacerlo y contenta de que estas fiestas la encuentren en casa\u00bb -dice su mama emocionada-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-394b7887cd896eb1b29427040afc69a2\"><strong>NOTA A FLOR MOR\u00d3N<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Ameghino: Flor Mor\u00f3n: Pedaleando recorri\u00f3 Argentina y Brasil, regres\u00f3 despues de tres a\u00f1os\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/_lO6bFNYdWI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ella es Flor Mor\u00f3n, 24 a\u00f1os, gastron\u00f3mica de profesi\u00f3n, hace tres a\u00f1os parti\u00f3 de su casa en Ameghino como mochilera a cumplir con su objetivo, recorrer el pais, llegar a Brasil, viviendo de su arte. \u00abSiempre dije que un dia quer\u00eda hacer esta experiencia, cuando me recib\u00ed, agarre una mochila, una bolsa de dormir, mis [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,31,6,9,37],"tags":[],"class_list":["post-9262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-florentino-ameghino","category-importantes","category-interes-general","category-municipios","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/FLORRRVALIDA.jpeg?fit=726%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=9262"}],"version-history":[{"count":2,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9262\/revisions"}],"predecessor-version":[{"id":9271,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9262\/revisions\/9271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/9264"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=9262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=9262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=9262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}