{"id":9298,"date":"2023-12-23T07:25:45","date_gmt":"2023-12-23T10:25:45","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=9298"},"modified":"2023-12-27T22:46:20","modified_gmt":"2023-12-28T01:46:20","slug":"noche-buena-se-esperan-tormentas-en-el-centro-del-pais-y-ya-rige-un-alerta","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/interes-general\/noche-buena-se-esperan-tormentas-en-el-centro-del-pais-y-ya-rige-un-alerta\/","title":{"rendered":"Noche Buena: se esperan tormentas en el centro del pa\u00eds y ya rige un alerta"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-744e05c60f48f0de1d6d0ac67f38d00d\"><em>El Servicio Meteorol\u00f3gico Nacional (SMN) emiti\u00f3 este viernes\u00a0<strong>un alerta de nivel amarillo por tormentas para la tarde y la noche del domingo 24 de diciembre<\/strong>. La zonas bajo alerta son el sur y centro de la provincia de Buenos Aires, centro y este de La Pampa, este de R\u00edo Negro, sur de Santa Fe y sur de C\u00f3rdoba<\/em><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-35284b3b805b52d25157a374d58dcc61\">De acuerdo a las previsiones actuales, a partir de la tarde del domingo, el avance de un frente fr\u00edo desde el noreste de Patagonia hasta el sur del litoral, provocar\u00e1 lluvias y tormentas de variada intensidad en varios sectores de la franja central.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d22fe9302e25f5b646e9badc16361fa7\">Algunas de las tormentas pueden ser localmente fuertes y estar acompa\u00f1adas por intensa actividad el\u00e9ctrica, r\u00e1fagas que pueden superar los 80 km\/h, y granizo de manera localizada. Los valores de precipitaci\u00f3n acumulada estar\u00e1n entre los 30 y 60 mm, aunque pueden ser superados en forma puntual.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3eaa9dfb712b5261061e55ccf69b9d39\">Existe cierta incertidumbre en los modelos num\u00e9ricos, que a\u00fan no pueden determinar con precisi\u00f3n el \u00e1rea total que ser\u00e1 afectada por los fen\u00f3menos m\u00e1s intensos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio Meteorol\u00f3gico Nacional (SMN) emiti\u00f3 este viernes\u00a0un alerta de nivel amarillo por tormentas para la tarde y la noche del domingo 24 de diciembre. La zonas bajo alerta son el sur y centro de la provincia de Buenos Aires, centro y este de La Pampa, este de R\u00edo Negro, sur de Santa Fe y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[38,31,6,37],"tags":[],"class_list":["post-9298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","category-importantes","category-interes-general","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/MAPAAVALIDO.png?fit=498%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=9298"}],"version-history":[{"count":1,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9298\/revisions"}],"predecessor-version":[{"id":9300,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9298\/revisions\/9300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/9299"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=9298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=9298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=9298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}