{"id":9340,"date":"2023-12-28T09:36:25","date_gmt":"2023-12-28T12:36:25","guid":{"rendered":"https:\/\/www.labrujulaweb.com.ar\/blog\/?p=9340"},"modified":"2023-12-29T07:18:55","modified_gmt":"2023-12-29T10:18:55","slug":"tres-algarrobos-metalurgica-zabala-resultado-del-complemento-entre-experiencia-tenas-y-juventud-nota","status":"publish","type":"post","link":"https:\/\/www.labrujulaweb.com.ar\/blog\/destacadas\/tres-algarrobos-metalurgica-zabala-resultado-del-complemento-entre-experiencia-tenas-y-juventud-nota\/","title":{"rendered":"Tres Algarrobos \u201cMetal\u00fargica Zabala\u201d resultado del complemento entre experiencia tenas y juventud .(nota)"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-799f1a057138ef6e7744abc5e0d025d5\">Luis Zabala comenz\u00f3 hace m\u00e1s de 40 a\u00f1os con un taller de maquinarias agr\u00edcolas, hoy \u2013junto a dos de sus hijas es el responsable de <strong>\u201cConstrucciones Metal\u00fargica Zabala\u201d<\/strong> que engalana una de las empresas destacadas en <strong>Tres Algarrobos, <\/strong>partido de Caros Tejedor.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-733a563369227a76ae38b03aae4c33e5\">\u201cEmpec\u00e9 con una sociedad <strong>\u201cAlemani-Zabala\u201d<\/strong> con un taller de reparaci\u00f3n de maquinarias, estuvimos juntos durante 5 a\u00f1os y luego, hace 43 a\u00f1os segu\u00ed con la metal\u00fargica, hasta el d\u00eda de hoy en que ya soy como un responsable a medias\u201d-dice Luis con humor- porque las hijas se hacen cargo de la parte administrativa y trato con proveedores y clientes-comienza diciendo Luis-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f9db187217261c083214e5ce64dd3e4c\">\u201cJunto a Alicia- mi esposa que hoy ya no est\u00e1-nos sacrificamos mucho para ir creciendo y hoy nuestro fruto se ve, somos una empresa familiar que concentra a 12 empleados directos, dos de nuestras hijas trabajan aqu\u00ed y siempre estamos apostando a crecer\u201d.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-af5dd7dca7998c2093d7ecd46ea3b9ff\">\u201cHemos pasado por varias crisis econ\u00f3micas en el pa\u00eds y de todas hemos podido salir, las empresas cuando vienen organizadas, generalmente no nos va mal, quiz\u00e1 con altibajos, pero siempre preparados para afrontar y sobrellevar situaciones dif\u00edciles con responsabilidad, hemos tenidos a\u00f1os muy buenos en los que crecimos y en otros nos mantenemos\u201d- reflexiona Luis-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-0926e102161a66bac59f21a5eefe47ac\">Actualmente est\u00e1n incorporadas a la empresa dos de sus cuatro hijas, <strong>Valeria y Natalia Zabala, <\/strong>quienes despu\u00e9s de formarse en sus estudios fuera de la ciudad, volvieron a su pueblo natal y se encuentran al frente de la metal\u00fargica que destaca sus verdes colores en el acceso de ingreso de Tres Algarrobos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3816b56db6d9932408db7bdd4cf58cef\">\u201cYa hace once a\u00f1os que estoy y tuve la suerte de venirme cuando la empresa estaba en expansi\u00f3n, mud\u00e1ndose a este nuevo espacio, m\u00e1s confortable para trabajar, siempre supe que volver\u00eda a mi terru\u00f1o, en los primeros a\u00f1os m\u00edos aqu\u00ed, vi un importante crecimiento, estos \u00faltimos tres a\u00f1os han sido m\u00e1s duros, estamos muy relacionados al campo y la sequ\u00eda y la econom\u00eda inestable no nos ha favorecido, el trabajo se ha vuelto m\u00e1s dif\u00edcil en el d\u00eda a d\u00eda y eso no nos permite planificar o pensar a futuro\u201d- confiesa Valeria-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a8c59fb776ce205e74c1656446ac1b96\">\u201cAqu\u00ed tenemos repartidos los roles de trabajo yo y mi hermana Natalia estamos a cargo de lo administrativo financiero, nos manejamos comercialmente con proveedores y papa est\u00e1 siempre en el sector productivo ya sea el manejo del personal de taller de reparaciones, fabricaci\u00f3n de galones y tinglados\u201d.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-86f695399a3d0881020eb4ae2b78bb2c\">En cuanto a la relaci\u00f3n comercial que ambos tienen Valeria asegura que \u201cahora nos complementamos mejor, \u00a0aunque en los primeros a\u00f1os nos pele\u00e1bamos m\u00e1s, yo ven\u00eda con una experiencia diferente, la de trabajar en empresas multinacionales en Bs As, que es otra realidad, el cliente all\u00ed es un n\u00famero, aqu\u00ed sin embargo con el cliente se entabla una relaci\u00f3n de amistad y hasta a veces familiar y hay una visi\u00f3n no solo comercial, sino de solucionarle el problema, m\u00e1s all\u00e1 de vender un producto o un servicio\u201d-asegura-<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Luis y Valeria Zabala- Tres Algarrobos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/lR2r29gN7zU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8fd07188eb3bac757f98eedf7a02d4ab\">En tanto Luis, reconoce que el arribo de Valeria a la empresa trajo un orden administrativo que le ayud\u00f3 a resolver muchos obst\u00e1culos econ\u00f3micos que se hab\u00edan dado- junto a su esposa- por la expansi\u00f3n de la metal\u00fargica \u201cA m\u00ed me costaba ocuparme de los cobros, yo ten\u00eda con el cliente una relaci\u00f3n de amistad y se me iba atrasando el ingreso de cheques, en esa \u00e9poca los sistemas de pagos eran diferentes, realmente con <strong>Valeria y Natalia<\/strong> eso fue cambiando y nos favoreci\u00f3. Hace 11 a\u00f1os cuando ella lleg\u00f3 ac\u00e1, le dej\u00e9 todo arriba del escritorio y no me ocup\u00e9 m\u00e1s de la parte comercial, no entr\u00e9 nunca m\u00e1s al banco \u201c-expresa Luis con \u00e9nfasis-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8637f6885a8567ac1c131a6c47c0229e\">En el mismo sentido y reconociendo que ambos aprenden el uno del otro, Valeria asegura que de Luis aprendi\u00f3 la tenacidad. \u201cMi papa es muy tenaz, en cambio yo soy m\u00e1s conservadora, el encara y le mete para adelante, siempre y en general, no s\u00e9 si por suerte o sabidur\u00eda, no la pifia tanto- dice entre risas- antes se complementaba con mi mam\u00e1, quien colaboraba en lo administrativo, hoy lo hace conmigo, yo a veces lo freno un poco, contemplo y analizo m\u00e1s, \u00e9l es m\u00e1s euf\u00f3rico en eso, as\u00ed hacemos un buen equipo de trabajo\u201d<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d0c2747118fa5b48ca103daaabc11f3d\">En cuanto a la visi\u00f3n de futuro Luis asegura tener muchas expectativas, \u201cNo va a ser f\u00e1cil, pero me entusiasma que hayamos cambiado el camino, que busquemos otra l\u00ednea, si bien esto nos va a doler mucho, veo otra manera de salir de un estanco\u201d-reflexiona-<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9f4ab437bc290bf5cccb2b797bec7b46\">\u201cEn tanto Valeria aporta que \u201c Es dif\u00edcil en este momento de cimbronazo econ\u00f3mico poder proyectar cosas buenas, porque yo no miro por mi sola, nuestro trabajo en particular depende adem\u00e1s de la situaci\u00f3n macroecon\u00f3mica y pol\u00edtica, de c\u00f3mo le vaya a campo y ese sector depende muchas veces de las condiciones clim\u00e1ticas, por lo que, si hay una mala campa\u00f1a y una buena pol\u00edtica no se siente tanto , en este momento uno mira m\u00e1s all\u00e1 de eso y ah\u00ed veo un a\u00f1o dif\u00edcil por delante, aunque tenemos que esperar lo bueno y trabajar cada uno en lo que sabemos hacer, lo mejor que podamos .<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"333\" src=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/ZABALAAA.jpg?resize=640%2C333&#038;ssl=1\" alt=\"\" class=\"wp-image-9351\" style=\"width:436px;height:auto\" srcset=\"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/ZABALAAA.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/ZABALAAA.jpg?resize=300%2C156&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/ZABALAAA.jpg?resize=768%2C400&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-ba352c2a7702e25ab7587ec5254bdab4\">En cuanto al deseo para el 2024 ambos coinciden en que <strong>esperan generar m\u00e1s fuente de trabajo<\/strong>, \u201cPara eso esperamos una estabilidad econ\u00f3mica que permita lograrlo, ya que ha sido el objetivo principal del crecimiento de esta empresa-concluyen-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Zabala comenz\u00f3 hace m\u00e1s de 40 a\u00f1os con un taller de maquinarias agr\u00edcolas, hoy \u2013junto a dos de sus hijas es el responsable de \u201cConstrucciones Metal\u00fargica Zabala\u201d que engalana una de las empresas destacadas en Tres Algarrobos, partido de Caros Tejedor. \u201cEmpec\u00e9 con una sociedad \u201cAlemani-Zabala\u201d con un taller de reparaci\u00f3n de maquinarias, estuvimos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-9340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.labrujulaweb.com.ar\/blog\/wp-content\/uploads\/2023\/12\/METALURGICAZABAVALIDA.jpg?fit=889%2C500&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=9340"}],"version-history":[{"count":3,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9340\/revisions"}],"predecessor-version":[{"id":9353,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/posts\/9340\/revisions\/9353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media\/9341"}],"wp:attachment":[{"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=9340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=9340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labrujulaweb.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=9340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}